{"id":213989,"date":"2024-08-02T16:54:53","date_gmt":"2024-08-02T15:54:53","guid":{"rendered":"https:\/\/groupe-reussite.fr\/ressources\/?page_id=213989"},"modified":"2024-11-14T13:21:04","modified_gmt":"2024-11-14T12:21:04","slug":"cp-francais-spinoza-prepa-analyse","status":"publish","type":"page","link":"https:\/\/groupe-reussite.fr\/ressources\/cp-francais-spinoza-prepa-analyse\/","title":{"rendered":"R\u00e9sum\u00e9 analyse Spinoza"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"213989\" class=\"elementor elementor-213989\">\n\t\t\t\t\n\t\t<script type=\"text\/javascript\">\n\t\t\tjQuery(document).ready(function() {\n\n\t\t\t\tjQuery(\".elementor-element-6fe69c56\").prepend('<div class=\"aepro-section-bs\"><div class=\"aepro-section-bs-inner\"><\/div><\/div>');\n\t\t\t\tvar bgimage = '';\n\t\t\t\tif ('yes' == 'yes') {\n\n\t\t\t\t\t\/\/if(bgimage == ''){\n\t\t\t\t\t\/\/    var bgoverlay = '';\n\t\t\t\t\t\/\/}else{\n\t\t\t\t\tvar bgoverlay = 'https:\/\/groupe-reussite.fr\/ressources\/wp-content\/plugins\/anywhere-elementor-pro\/includes\/assets\/lib\/vegas\/overlays\/00.png';\n\t\t\t\t\t\/\/ }\n\t\t\t\t} else {\n\t\t\t\t\tif ('') {\n\t\t\t\t\t\tvar bgoverlay = 'https:\/\/groupe-reussite.fr\/ressources\/wp-content\/plugins\/anywhere-elementor-pro\/includes\/assets\/lib\/vegas\/overlays\/.png';\n\t\t\t\t\t} else {\n\t\t\t\t\t\tvar bgoverlay = 'https:\/\/groupe-reussite.fr\/ressources\/wp-content\/plugins\/anywhere-elementor-pro\/includes\/assets\/lib\/vegas\/overlays\/00.png';\n\t\t\t\t\t}\n\t\t\t\t}\n\n\n\t\t\t\tjQuery(\".elementor-element-6fe69c56\").children('.aepro-section-bs').children('.aepro-section-bs-inner').vegas({\n\t\t\t\t\tslides: [{\"src\":\"https:\\\/\\\/groupe-reussite.fr\\\/ressources\\\/wp-content\\\/uploads\\\/2017\\\/11\\\/stage-maths-sup-spe-banniere-3.jpg\"}],\n\t\t\t\t\ttransition: 'fade',\n\t\t\t\t\tanimation: 'kenburns',\n\t\t\t\t\toverlay: bgoverlay,\n\t\t\t\t\tcover: true,\n\t\t\t\t\tdelay: 5000,\n\t\t\t\t\ttimer: true\t\t\t\t});\n\t\t\t\tif ('yes' == 'yes') {\n\t\t\t\t\tjQuery(\".elementor-element-6fe69c56\").children('.aepro-section-bs').children('.aepro-section-bs-inner').children('.vegas-overlay').css('background-image', '');\n\t\t\t\t}\n\t\t\t});\n\t\t<\/script>\n\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-6fe69c56 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"6fe69c56\" data-element_type=\"section\" data-e-type=\"section\" id=\"header_height\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-75db7b60 ae-bg-gallery-type-default\" data-id=\"75db7b60\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-711e6392 elementor-widget elementor-widget-heading\" data-id=\"711e6392\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Analyse du Trait\u00e9 th\u00e9ologico-politique de Spinoza th\u00e8me fran\u00e7ais pr\u00e9pa 2024<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a6c4711 elementor-widget elementor-widget-heading\" data-id=\"3a6c4711\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Trait\u00e9 th\u00e9ologico-politique\u00a0: personnages, r\u00e9sum\u00e9 et individu et communaut\u00e9 en pr\u00e9pa<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1505175 elementor-widget elementor-widget-text-editor\" data-id=\"1505175\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"112233\" class=\"elementor elementor-112233\">\n\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-inner-section elementor-element elementor-element-2753c5f2 elementor-section-content-bottom elementor-section-full_width elementor-section-height-min-height elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"2753c5f2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-27ee3c1b ae-bg-gallery-type-default\" data-id=\"27ee3c1b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c70fc7d elementor-align-center elementor-widget elementor-widget-button\" data-id=\"4c70fc7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md elementor-animation-grow\" href=\"https:\/\/groupe-reussite.fr\/cours-particuliers\/francais\/tous-niveaux\/france\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-bookmark\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Trouver des professeurs particuliers de fran\u00e7ais<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p><div id=\"gtx-trans\"><div class=\"gtx-trans-icon\">\u00a0<\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-2305ac68 elementor-section-full_width sticky_page elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"2305ac68\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-35198305 col_height ae-bg-gallery-type-default\" data-id=\"35198305\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-inner-section elementor-element elementor-element-2197c53 elementor-section-content-middle wrap elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"2197c53\" data-element_type=\"section\" data-e-type=\"section\" id=\"sticky_sidebar\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6fbd9567 hide_col ae-bg-gallery-type-default\" data-id=\"6fbd9567\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6991ab73 strick_col ae-bg-gallery-type-default\" data-id=\"6991ab73\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d48515d elementor-widget elementor-widget-image\" data-id=\"5d48515d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"210\" src=\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2020\/03\/cours-particuliers.jpg\" class=\"attachment-large size-large wp-image-44782\" alt=\"cours-particulier-paris\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3b7cd6dc elementor-widget elementor-widget-heading\" data-id=\"3b7cd6dc\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"cat_name\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">cours particuliers<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1849402b elementor-widget elementor-widget-heading\" data-id=\"1849402b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Cours particuliers de fran\u00e7ais<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-242132dc elementor-align-center elementor-widget elementor-widget-button\" data-id=\"242132dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/groupe-reussite.fr\/cours-particuliers\/francais\/tous-niveaux\/france\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">R\u00e9server un cours particulier de fran\u00e7ais<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db0b061 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"db0b061\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/groupe-reussite.fr\/nous-contacter\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">CONTACTEZ  NOUS<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-12987e37 section_width ae-bg-gallery-type-default\" data-id=\"12987e37\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-inner-section elementor-element elementor-element-1e473da0 elementor-section-content-middle full_width elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"1e473da0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-240e788 ae-bg-gallery-type-default\" data-id=\"240e788\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12cd6bd elementor-widget elementor-widget-text-editor\" data-id=\"12cd6bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Le Trait\u00e9 th\u00e9ologico-politique : CPGE fran\u00e7ais Spinoza<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-317fa871 elementor-widget elementor-widget-text-editor\" data-id=\"317fa871\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Le contenu du <strong>programme de fran\u00e7ais-philosophie<\/strong> pour les classes pr\u00e9paratoires scientifiques (MPSI, PCSI, PTSI, BCPST, MP2I, MP, MPI, PC, PSI et PT) a r\u00e9cemment \u00e9t\u00e9 divulgu\u00e9. Le th\u00e8me central sera \u00ab <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cp-francais-theme-individu-et-communaute-cpge\/\">Individu et Communaut\u00e9<\/a> \u00bb. L&rsquo;une des quatre \u0153uvres que les taupins devront \u00e9tudier est <strong><em>Le Trait\u00e9 th\u00e9ologico-politique<\/em>, sections 16 \u00e0 20 <\/strong>de Spinoza.<\/p><p>Apr\u00e8s un tour d\u2019horizon philosophique pour nourrir votre culture g\u00e9n\u00e9rale dans la pr\u00e9sentation du th\u00e8me de l&rsquo;ann\u00e9e 2024 2025, nous vous proposons, dans cet article, une <strong>pr\u00e9sentation de l\u2019\u0153uvre <em>Trait\u00e9 th\u00e9ologico-politique<\/em> de Spinoza<\/strong> \u00e0 la lumi\u00e8re du th\u00e8me \u00ab Individu et Communaut\u00e9 \u00bb en CPGE.<\/p><p>Les \u00e9l\u00e8ves qui font appel aux <a href=\"https:\/\/groupe-reussite.fr\/cours-particuliers\/francais\/tous-niveaux\/france\/\">cours particuliers de fran\u00e7ais<\/a> avec Groupe R\u00e9ussite gagnent en moyenne 4 points aux concours et arrivent souvent \u00e0 int\u00e9grer de bonnes \u00e9coles notamment gr\u00e2ce au fran\u00e7ais qui poss\u00e8de de tr\u00e8s forts coefficients aux concours Centrale Supelec, Mines Ponts ou encore X ENS et CCINP.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c583f03 elementor-widget elementor-widget-text-editor\" data-id=\"c583f03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"text-align: justify\">Individu et communaut\u00e9 pr\u00e9pa : Spinoza, le libre-penseur h\u00e9r\u00e9tique ?<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eda5a88 elementor-widget elementor-widget-text-editor\" data-id=\"eda5a88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: justify;\"><strong>Baruch Spinoza<\/strong> (1632-1677), en d\u00e9pit de sa vie relativement courte, a marqu\u00e9 l\u2019histoire des id\u00e9es et de la philosophe. Il s\u2019inscrit pleinement dans la lign\u00e9e de Descartes \u2013 dans la lign\u00e9e du rationalisme cart\u00e9sien \u2013 et son \u0153uvre sera reprise et admir\u00e9e notamment par Leibniz, toujours au XVIIe si\u00e8cle.<\/p><h3><strong>1632 : Naissance de Baruch Spinoza \u00e0 Amsterdam<\/strong><\/h3><p>Spinoza vient du portugais \u00ab espinosa \u00bb, qui signifie \u00ab \u00e9pineux \u00bb \u2026 et en effet, la vie de Spinoza allait d\u00e9ranger nombre de ses concitoyens et notamment coreligionnaires. Spinoza na\u00eet en effet dans une famille de commer\u00e7ants juifs, \u00e0 Amsterdam. Pourquoi le portugais est-il sa langue natale ? Car les Juifs marranes de la famille de Spinoza avaient fui l\u2019Espagne en 1492 (les Juifs furent expuls\u00e9s du Royaume cette ann\u00e9e-l\u00e0) puis du Portugal en 1593 (suite \u00e0 une nouvelle expulsion). L\u2019ouverture religieuse, la tol\u00e9rance des opinions, joueront ainsi un r\u00f4le non seulement dans la vie, mais encore dans la pens\u00e9e de Spinoza. Du reste, il existe une telle diversit\u00e9 d\u2019opinions et de religions \u00e0 Amsterdam que cela conduira aussi Spinoza \u00e0 penser que la libert\u00e9 de penser, la diversit\u00e9 des opinions, ne nuisent pas forc\u00e9ment \u00e0 la stabilit\u00e9 de l\u2019\u00c9tat.<\/p><p>\t\t<div data-elementor-type=\"section\" data-elementor-id=\"190576\" class=\"elementor elementor-190576\">\n\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-inner-section elementor-element elementor-element-23d5e658 elementor-section-content-bottom full_width elementor-section-full_width elementor-section-height-min-height elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"23d5e658\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-64e6e5b7 ae-bg-gallery-type-default\" data-id=\"64e6e5b7\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4100214c elementor-widget elementor-widget-heading\" data-id=\"4100214c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">PROFS DE FRANCAIS A PROXIMITE<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43840f5e elementor-widget elementor-widget-heading\" data-id=\"43840f5e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">R\u00e9servez les <b> meilleurs profs de fran\u00e7ais<\/b><\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4dbbd556 elementor-widget elementor-widget-heading\" data-id=\"4dbbd556\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">S&rsquo;am\u00e9liorer et viser l&rsquo;excellence<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b966d8d elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"5b966d8d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/groupe-reussite.fr\/cours-particuliers\/francais\/tous-niveaux\/france\/\" target=\"_blank\" id=\"CTA_PRD_CP\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Prof de fran\u00e7ais<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e05a9e7 elementor-widget elementor-widget-text-editor\" data-id=\"7e05a9e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><b>Avis Google France <\/b><span style=\"color: #e5a430;\"><b>\u2605\u2605\u2605\u2605\u2605<\/b><\/span><b> 4,8 sur 5<\/b><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-389e36d0 ae-bg-gallery-type-default\" data-id=\"389e36d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p><h3><strong>1654 : Mort du p\u00e8re de Spinoza<\/strong><\/h3><p>Cons\u00e9quemment, Spinoza, sans doute brillant \u00e9tudiant, dut vite reprendre les affaires commerciales familiales, en d\u00e9pit de sa sant\u00e9 fragile. N\u00e9anmoins, ce bouleversement n\u2019emp\u00eacha Spinoza de parfaire sa formation. Il apprit bien s\u00fbr la Bible, l\u2019h\u00e9breu, les sources rabbiniques, et m\u00eame l\u2019espagnol et le n\u00e9erlandais.<\/p><p>Cependant, il s\u2019ouvrit aussi \u00e0 des lectures \u2018profanes\u2019 voire dangereuses pour l\u2019orthodoxie religieuse. Notamment sous l\u2019influence du pr\u00eatre j\u00e9suite Franciscus Van den Enden, il s\u2019ouvre aux id\u00e9es d\u00e9mocratiques, \u00e0 l\u2019h\u00e9ritage antique de Gr\u00e8ce et de Rome, \u00e0 Bacon, Galil\u00e9e et Giordano Bruno ou encore \u00e0 la philosophie politique de Machiavel, Hobbes, Grotius ou More.<\/p><p>Autant d\u2019id\u00e9es sulfureuses \u00e0 l\u2019\u00e9poque : pour rappel, Galil\u00e9e a failli finir br\u00fbl\u00e9 pour avoir clam\u00e9 que la Terre n&rsquo;\u00e9tait pas au centre de l\u2019univers\u2026 et Bruno a, lui, bien fini sur le b\u00fbcher pour avoir \u00e9voqu\u00e9 la \u00ab pluralit\u00e9 des mondes \u00bb.<\/p><figure id=\"attachment_214003\" aria-describedby=\"caption-attachment-214003\" style=\"width: 258px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-214003 size-medium\" src=\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2024\/07\/cpge-francais-spinoza-258x300.jpg\" alt=\"Cpge fran\u00e7ais spinoza\" width=\"258\" height=\"300\" srcset=\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2024\/07\/cpge-francais-spinoza-258x300.jpg 258w, https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2024\/07\/cpge-francais-spinoza.jpg 602w\" sizes=\"(max-width: 258px) 100vw, 258px\" \/><figcaption id=\"caption-attachment-214003\" class=\"wp-caption-text\">Spinoza vient du portugais espinosa, \u00ab \u00e9pineux \u00bb. Et en effet, sa pens\u00e9e a \u00ab piqu\u00e9 \u00bb nombre de ses contemporains \u2013 et notamment coreligionnaires.<\/figcaption><\/figure><h3><strong>1656 : Excommunication (herem) de Spinoza par la communaut\u00e9 juive<\/strong><\/h3><p>La sanction est rare et gravissime : Spinoza est excommuni\u00e9. Les raisons n&rsquo;en sont pas pr\u00e9cis\u00e9ment connues. Mais m\u00eame s\u2019il n\u2019a rien encore publi\u00e9, on peut se douter que les id\u00e9es de \u00ab libre-penseur \u00bb de Spinoza sont en cause. Il aurait remis en question le caract\u00e8re litt\u00e9ral de la Bible ou des grands dogmes fondateurs : comme l\u2019immoralit\u00e9 de l\u2019\u00e2me, le statut \u00ab \u00e9lu \u00bb du peuple juif, etc\u2026 Ses id\u00e9es \u00e9taient donc consid\u00e9r\u00e9es comme h\u00e9r\u00e9tiques et mena\u00e7antes pour l&rsquo;ordre communautaire. La vie m\u00eame de Spinoza est donc une sorte de dissociation d\u2019un individu d\u2019une communaut\u00e9.<\/p><p>Lire \u00e9galement : <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cp-francais-citations-individu-communaute-prepa\/\">Citations individu et communaut\u00e9<\/a><\/p><h3><strong>1660 : Spinoza s&rsquo;installe \u00e0 Rijnsburg, aux Pays-Bas<\/strong><\/h3><p>Les Pays-Bas sont alors non seulement une capitale commerciale, mais aussi une capitale intellectuelle \u2013 c&rsquo;est le Royaume o\u00f9 les \u00e9crits sont les plus libres du monde et o\u00f9 les intellectuels se croisent.<\/p><p>Spinoza \u00e9tudie les \u0153uvres de Descartes, qui influenceront profond\u00e9ment sa pens\u00e9e. M\u00eame si Descartes ne remet pas en cause l\u2019existence de Dieu, pour lui, l\u2019origine de toute connaissance, de \u00ab quelque chose de durable et certain dans les sciences \u00bb, provient de l\u2019autonomie de la pens\u00e9e humaine, qui doit se lib\u00e9rer de ses pr\u00e9jug\u00e9s en interrogeant les conditions de leur formation. Descartes influencera aussi Spinoza dans sa mani\u00e8re de penser, tr\u00e8s rationnelle, d\u00e9ductive et g\u00e9om\u00e9trique.<\/p><p>C&rsquo;est ainsi que dans la plupart de ses \u0153uvres, Spinoza adoptera un \u00ab raisonnement \u00e0 la mani\u00e8re g\u00e9om\u00e9trique \u00bb (de more geometrico), c&rsquo;est-\u00e0-dire en formalisant les hypoth\u00e8ses, les preuves, les d\u00e9ductions, etc.<\/p><p>Spinoza fait publier les <em>Principes de la philosophie de Descartes<\/em>, la seule \u0153uvre publi\u00e9e de son vivant sous son nom, en 1663.<\/p><h3><strong>1670 : Publication anonyme du <em>Trait\u00e9 th\u00e9ologico-politique<\/em><\/strong><\/h3><p>Cet ouvrage, nous le verrons, fait scandale. Il critique la superstition et promeut une vision de la religion compatible avec la raison, plaidant pour la libert\u00e9 de pens\u00e9e et une s\u00e9paration entre l&rsquo;\u00c9glise et l&rsquo;\u00c9tat.<\/p><p>En 1673, Spinoza est invit\u00e9 \u00e0 devenir professeur de philosophie \u00e0 l&rsquo;Universit\u00e9 de Heidelberg, mais il refuse pour pr\u00e9server sa libert\u00e9 de pens\u00e9e.<\/p><figure id=\"attachment_214004\" aria-describedby=\"caption-attachment-214004\" style=\"width: 211px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-214004 size-medium\" src=\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2024\/07\/cpge-francais-spinoza-1-211x300.jpg\" alt=\"cpge fran\u00e7ais spinoza\" width=\"211\" height=\"300\" srcset=\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2024\/07\/cpge-francais-spinoza-1-211x300.jpg 211w, https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2024\/07\/cpge-francais-spinoza-1.jpg 493w\" sizes=\"(max-width: 211px) 100vw, 211px\" \/><figcaption id=\"caption-attachment-214004\" class=\"wp-caption-text\">Conscient du caract\u00e8re \u00e9minemment sulfureux de son ma\u00eetre-ouvrage, Spinoza ne fera publier <em>L\u2019\u00c9thique<\/em> (ouvrage r\u00e9dig\u00e9 en latin) qu&rsquo;apr\u00e8s sa mort.<\/figcaption><\/figure><h3><strong>1675 : Ach\u00e8vement de <em>L\u2019\u00c9thique<\/em>, son \u0153uvre majeure<\/strong><\/h3><p>Mais elle sera publi\u00e9e de mani\u00e8re <strong>posthume<\/strong> pour \u00e9viter la censure\u2026 voire pire ! Empruntant au rationalisme, \u00e0 l\u2019humanisme ou au scepticisme, Spinoza syst\u00e9matise sa vision du monde : celle de Dieu, de la nature, de l\u2019humain, de la morale, de la religion, de la m\u00e9taphysique, etc. La raison humaine s\u2019\u00e9l\u00e8ve au-dessus des principes et pr\u00e9jug\u00e9s h\u00e9rit\u00e9s.<\/p><p>Spinoza se propose par exemple d\u2019examiner par la raison les miracles suppos\u00e9s, comme dans cet extrait de <em>L\u2019\u00c9thique<\/em> : \u00ab C\u2019est pourquoi quiconque cherche les v\u00e9ritables causes des miracles, et s\u2019efforce de comprendre les choses naturelles en philosophe, au lieu de les admirer en homme stupide, est tenu aussit\u00f4t pour h\u00e9r\u00e9tique et pour impie, et proclam\u00e9 tel par les hommes que le vulgaire adore comme les interpr\u00e8tes de la nature et de Dieu. Ils savent bien, en effet, que l\u2019ignorance, une fois disparue, ferait dispara\u00eetre \u00e0 son tour l\u2019\u00e9tonnement, c\u2019est-\u00e0-dire l\u2019unique base de tous leurs arguments, l\u2019unique appui de leur autorit\u00e9. \u00bb On comprend bien le scandale potentiel !<\/p><p>Il propose une <strong>conception de Dieu int\u00e9gr\u00e9e dans la nature<\/strong> (<em>Deus sive Natura<\/em>), \u00e9liminant la distinction entre cr\u00e9ation et cr\u00e9ateur \u2013 il promeut une vision que l\u2019on pourrait qualifier de vision panth\u00e9iste de l&rsquo;univers. Pour Spinoza, Dieu est la force, la puissance qui produit l\u2019ensemble de la nature de fa\u00e7on rationnelle et n\u00e9cessaire \u2013 rendant possible une compr\u00e9hension du r\u00e9el sur une base rationnelle.<\/p><h3>1677 : D\u00e9c\u00e8s de Spinoza \u00e0 La Haye et publication de <strong>L\u2019\u00c9thique<\/strong> \u00e0 sa mort<\/h3><figure id=\"attachment_214005\" aria-describedby=\"caption-attachment-214005\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-214005 size-medium\" src=\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2024\/07\/prepa-francais-spinoza-300x275.jpg\" alt=\"Cpge fran\u00e7ais spinoza\" width=\"300\" height=\"275\" srcset=\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2024\/07\/prepa-francais-spinoza-300x275.jpg 300w, https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2024\/07\/prepa-francais-spinoza.jpg 547w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption id=\"caption-attachment-214005\" class=\"wp-caption-text\">L\u2019exemple de la \u00ab pierre qui tombe \u00bb est un des passages les plus fameux de l\u2019\u0153uvre de Spinoza.<\/figcaption><\/figure><h3>\u00a0<\/h3><p><strong>L\u2019Appendice du Livre I de <em>L\u2019\u00c9thique<\/em> de Spinoza :<\/strong><\/p><p><em>L\u2019\u00c9thique<\/em> est donc le livre, il est vrai, le plus fameux de Spinoza ; et dans cet ouvrage, l\u2019Appendice du Livre I l\u2019est en particulier. Dans cette sorte de pr\u00e9ambule, Spinoza d\u00e9construit le \u00ab <strong>pr\u00e9jug\u00e9 finaliste<\/strong> \u00bb de l\u2019homme. Auparavant, Spinoza, tout aussi libre-penseur qu&rsquo;il soit, a d\u00e9montr\u00e9 l\u2019existence n\u00e9cessaire de Dieu (toutes les choses d\u00e9pendent aussi de lui).<\/p><p>Ce pr\u00e9jug\u00e9 finaliste est ainsi r\u00e9sum\u00e9 par Spinoza : \u00ab les hommes supposent commun\u00e9ment que toutes les choses naturelles agissent comme eux, en vue d\u2019une fin, et bien plus, ils consid\u00e8rent que certain que Dieu dispose tout en vue d\u2019une certaine fin. \u00bb.<\/p><p>Or, nous dit le philosophe, tout dans la nature n&rsquo;a pas forc\u00e9ment de fin, d\u2019objectif ; il s\u2019agit d\u2019une reconstruction de l\u2019esprit afin de donner sens \u00e0 ce qui, parfois, n\u2019en a pas forc\u00e9ment. Il n\u2019y a pas de volont\u00e9 divine qui fait qu&rsquo;une pierre tombe par exemple (exemple repris par Spinoza) ; si une pierre tombe, ce n&rsquo;est pas par fatalit\u00e9 (le pr\u00e9jug\u00e9 finaliste), mais parce que les lois de la nature sont telles que la pierre tombe. Il n\u2019y a pas de dessein cach\u00e9, de fatalit\u00e9 l\u2019expliquant. Autrement dit, Spinoza assimile les lois de Dieu \u00e0 celles de la nature (c&rsquo;est donc son fameux : <em>Deus sive natura<\/em>, Dieu ou la nature).<\/p><p>Pour autant, les hommes continuent \u00e0 croire qu&rsquo;une pierre tombe parce qu&rsquo;elle \u00e9tait destin\u00e9e \u00e0 tomber. Pourquoi ? Car ils \u00ab plaquent \u00bb aux choses leur propre raisonnement : les hommes agissent toujours en vue d\u2019une fin, pour leur propre int\u00e9r\u00eat, donc ils pensent que tout a une fin dans l\u2019univers. Ils supposent partout des causes finales partout\u2026 Or, \u00e9crit Spinoza, \u00ab la nature ne se propose aucun but dans ses op\u00e9rations, et toutes les causes finales ne sont rien que de pures fictions imagin\u00e9es par les hommes. \u00bb<\/p><p>Et pourtant, les hommes n\u2019ont donc de cesse de rechercher des causes \u2013 jusqu&rsquo;\u00e0 remonter \u00e0 la premi\u00e8re, la volont\u00e9 de Dieu, que Spinoza surnomme \u00ab <strong>l\u2019asile de l&rsquo;ignorance<\/strong> \u00bb (\u00ab Et ainsi, ils ne cesseront de vous demander la cause de la cause, jusqu\u2019\u00e0 ce que vous recouriez \u00e0 la volont\u00e9 de Dieu, c\u2019est-\u00e0-dire \u00e0 l\u2019asile de l\u2019ignorance. \u00bb)<\/p><p>Spinoza souligne aussi que les hommes se pensent toujours libres \u2013 mais souvent parce qu&rsquo;ils ignorent les causes expliquant leurs propres actions (c\u2019est <strong>l\u2019illusion du libre-arbitre<\/strong>). Les hommes imaginent qu&rsquo;ils d\u00e9sirent telle ou telle chose, de leur propre gr\u00e9, alors que d\u2019autres facteurs ont influenc\u00e9 leur volont\u00e9 (cf. ce qu\u2019\u00e9crit Spinoza dans le m\u00eame appendice : \u00ab les hommes croient \u00eatre libres, par la raison qu\u2019ils ont conscience de leurs volitions [souhaits] et de leurs d\u00e9sirs, et ne pensent nullement aux causes qui les disposent \u00e0 d\u00e9sirer et \u00e0 vouloir. \u00bb)<\/p><p>Si Spinoza <strong>r\u00e9cuse la notion de libre-arbitre<\/strong>, il r\u00e9affirme cependant la possibilit\u00e9 d\u2019une libert\u00e9 humaine \u2013 pour Spinoza, est libre celui qui agit selon la seule n\u00e9cessit\u00e9 de sa propre nature (est captif celui qui agit non selon sa nature propre, mais en \u00e9tant soumis \u00e0 une nature ext\u00e9rieure et plus puissante).<\/p><figure id=\"attachment_214009\" aria-describedby=\"caption-attachment-214009\" style=\"width: 196px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-214009 size-medium\" src=\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2024\/07\/cpge-francais-spinoza-2-196x300.jpg\" alt=\"cpge fran\u00e7ais \" width=\"196\" height=\"300\" srcset=\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2024\/07\/cpge-francais-spinoza-2-196x300.jpg 196w, https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2024\/07\/cpge-francais-spinoza-2.jpg 391w\" sizes=\"(max-width: 196px) 100vw, 196px\" \/><figcaption id=\"caption-attachment-214009\" class=\"wp-caption-text\">La c\u00e9l\u00e8bre couverture du \u00ab L\u00e9viathan \u00bb de Hobbes pr\u00e9sente un souverain compos\u00e9 d\u2019une multitude d\u2019individus, comme si la communaut\u00e9 n\u2019\u00e9tait finalement que l\u2019agr\u00e9gat d\u2019individus s\u2019\u00e9tant volontairement fondus ensemble dans un seul et m\u00eame corps politique.<\/figcaption><\/figure>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d4ebf1 elementor-widget elementor-widget-text-editor\" data-id=\"5d4ebf1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 style=\"text-align: justify\">Fran\u00e7ais CPGE Spinoza : Analyse du<em>\u00a0Trait\u00e9 th\u00e9ologico-politique<\/em><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae93e9b elementor-widget elementor-widget-text-editor\" data-id=\"ae93e9b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Retrouvez la suite du contenu sur l\u2019analyse et le r\u00e9sum\u00e9 du <em>Trait\u00e9 th\u00e9ologico-politique<\/em> de Spinoza en pr\u00e9pa scientifique dans notre <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cp-cours-en-ligne-francais-cpge-ebook\/\">livre de fran\u00e7ais sur le th\u00e8me individu et communaut\u00e9<\/a>. Voici les \u00e9l\u00e9ments que vous y trouverez :\u00a0<\/p><h3>1. Spinoza, le libre-penseur h\u00e9r\u00e9tique ?<\/h3><h3>2. L\u2019h\u00e9ritage du contractualisme<\/h3><h3>3. Le TTP : comment concilier la libert\u00e9 naturelle de l\u2019individu avec les int\u00e9r\u00eats et la stabilit\u00e9 de la communaut\u00e9 ?<\/h3><h3>4. Le risque d\u2019un \u00c9tat trop r\u00e9pressif contre les individus<\/h3><h3>5. La fin de l\u2019\u00c9tat, c\u2019est la libert\u00e9 de l\u2019individu<\/h3><h3>6. La d\u00e9mocratie, r\u00e9gime le moins absurde en communaut\u00e9 ?<\/h3><p>Retrouvez d&rsquo;autres contenus sur le th\u00e8me de l&rsquo;ann\u00e9e 2024 2025 \u00e9galement pour vous aider \u00e0 pr\u00e9parer les concours :\u00a0<\/p><ul><li><a href=\"https:\/\/groupe-reussite.fr\/ressources\/cp-francais-eschyle-prepa-analyse\/\">Analyse et r\u00e9sum\u00e9 d&rsquo;Eschyle en CPGE<\/a><\/li><li><a href=\"https:\/\/groupe-reussite.fr\/ressources\/cp-francais-analyse-wharton-prepa\/\">Wharton th\u00e8me individu et communaut\u00e9 pr\u00e9pa<\/a><\/li><li><a href=\"https:\/\/groupe-reussite.fr\/ressources\/cp-francais-dissertation-individu-et-communaute-cpge\/\">Dissertation r\u00e9dig\u00e9e sur le th\u00e8me individu et communaut\u00e9<\/a><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Analyse du Trait\u00e9 th\u00e9ologico-politique de Spinoza th\u00e8me fran\u00e7ais pr\u00e9pa 2024 Trait\u00e9 th\u00e9ologico-politique\u00a0: personnages, r\u00e9sum\u00e9 et individu et communaut\u00e9 en pr\u00e9pa \u00a0 cours particuliers Cours particuliers de fran\u00e7ais R\u00e9server un cours particulier de fran\u00e7ais CONTACTEZ NOUS Le Trait\u00e9 th\u00e9ologico-politique : CPGE fran\u00e7ais Spinoza Le contenu du programme de fran\u00e7ais-philosophie pour les classes pr\u00e9paratoires scientifiques (MPSI, PCSI, [&hellip;]<\/p>\n","protected":false},"author":81,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"ocean_post_layout":"full-screen","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"off","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"on","ocean_disable_heading":"on","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","footnotes":""},"class_list":["post-213989","page","type-page","status-publish","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spinoza CPGE fran\u00e7ais : R\u00e9sum\u00e9 du Trait\u00e9 th\u00e9ologico-politique<\/title>\n<meta name=\"description\" content=\"Analyse d\u00e9taill\u00e9e du Trait\u00e9 th\u00e9ologico-politique par Spinoza en CPGE fran\u00e7ais sur le th\u00e8me individu et communaut\u00e9\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/groupe-reussite.fr\/ressources\/cp-francais-spinoza-prepa-analyse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spinoza CPGE fran\u00e7ais : R\u00e9sum\u00e9 du Trait\u00e9 th\u00e9ologico-politique\" \/>\n<meta property=\"og:description\" content=\"Analyse d\u00e9taill\u00e9e du Trait\u00e9 th\u00e9ologico-politique par Spinoza en CPGE fran\u00e7ais sur le th\u00e8me individu et communaut\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/groupe-reussite.fr\/ressources\/cp-francais-spinoza-prepa-analyse\/\" \/>\n<meta property=\"og:site_name\" content=\"Groupe R\u00e9ussite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GroupeReussiteOfficiel\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-14T12:21:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2020\/03\/cours-particuliers.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@GroupeReussite\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/groupe-reussite.fr\\\/ressources\\\/cp-francais-spinoza-prepa-analyse\\\/\",\"url\":\"https:\\\/\\\/groupe-reussite.fr\\\/ressources\\\/cp-francais-spinoza-prepa-analyse\\\/\",\"name\":\"Spinoza CPGE fran\u00e7ais : R\u00e9sum\u00e9 du Trait\u00e9 th\u00e9ologico-politique\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/groupe-reussite.fr\\\/ressources\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/groupe-reussite.fr\\\/ressources\\\/cp-francais-spinoza-prepa-analyse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/groupe-reussite.fr\\\/ressources\\\/cp-francais-spinoza-prepa-analyse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/groupe-reussite.fr\\\/ressources\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cours-particuliers.jpg\",\"datePublished\":\"2024-08-02T15:54:53+00:00\",\"dateModified\":\"2024-11-14T12:21:04+00:00\",\"description\":\"Analyse d\u00e9taill\u00e9e du Trait\u00e9 th\u00e9ologico-politique par Spinoza en CPGE fran\u00e7ais sur le th\u00e8me individu et communaut\u00e9\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/groupe-reussite.fr\\\/ressources\\\/cp-francais-spinoza-prepa-analyse\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/groupe-reussite.fr\\\/ressources\\\/cp-francais-spinoza-prepa-analyse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/groupe-reussite.fr\\\/ressources\\\/cp-francais-spinoza-prepa-analyse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/groupe-reussite.fr\\\/ressources\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cours-particuliers.jpg\",\"contentUrl\":\"https:\\\/\\\/groupe-reussite.fr\\\/ressources\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/cours-particuliers.jpg\",\"width\":300,\"height\":210,\"caption\":\"cours-particulier-paris\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/groupe-reussite.fr\\\/ressources\\\/cp-francais-spinoza-prepa-analyse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/groupe-reussite.fr\\\/ressources\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9sum\u00e9 analyse Spinoza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/groupe-reussite.fr\\\/ressources\\\/#website\",\"url\":\"https:\\\/\\\/groupe-reussite.fr\\\/ressources\\\/\",\"name\":\"Groupe R\u00e9ussite - Cours particuliers et stages de vacances\",\"description\":\"Stage et Cours particuliers maths, fran\u00e7ais, anglais, informatique, physique chimie\",\"publisher\":{\"@id\":\"https:\\\/\\\/groupe-reussite.fr\\\/ressources\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/groupe-reussite.fr\\\/ressources\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/groupe-reussite.fr\\\/ressources\\\/#organization\",\"name\":\"Groupe R\u00e9ussite - Cours particuliers et stages de vacances\",\"url\":\"https:\\\/\\\/groupe-reussite.fr\\\/ressources\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/groupe-reussite.fr\\\/ressources\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/groupe-reussite.fr\\\/ressources\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/logo-groupe-reussite-carre.png\",\"contentUrl\":\"https:\\\/\\\/groupe-reussite.fr\\\/ressources\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/logo-groupe-reussite-carre.png\",\"width\":170,\"height\":180,\"caption\":\"Groupe R\u00e9ussite - Cours particuliers et stages de vacances\"},\"image\":{\"@id\":\"https:\\\/\\\/groupe-reussite.fr\\\/ressources\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GroupeReussiteOfficiel\\\/\",\"https:\\\/\\\/x.com\\\/GroupeReussite\",\"https:\\\/\\\/www.youtube.com\\\/c\\\/GroupeReussite\",\"https:\\\/\\\/www.instagram.com\\\/groupe_reussite_officiel\\\/\",\"https:\\\/\\\/fr.linkedin.com\\\/company\\\/groupe-reussite\",\"https:\\\/\\\/www.tiktok.com\\\/@groupereussite\",\"https:\\\/\\\/fr.pinterest.com\\\/GroupeReussite\\\/\",\"https:\\\/\\\/www.reddit.com\\\/user\\\/Groupe-Reussite\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spinoza CPGE fran\u00e7ais : R\u00e9sum\u00e9 du Trait\u00e9 th\u00e9ologico-politique","description":"Analyse d\u00e9taill\u00e9e du Trait\u00e9 th\u00e9ologico-politique par Spinoza en CPGE fran\u00e7ais sur le th\u00e8me individu et communaut\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/groupe-reussite.fr\/ressources\/cp-francais-spinoza-prepa-analyse\/","og_locale":"fr_FR","og_type":"article","og_title":"Spinoza CPGE fran\u00e7ais : R\u00e9sum\u00e9 du Trait\u00e9 th\u00e9ologico-politique","og_description":"Analyse d\u00e9taill\u00e9e du Trait\u00e9 th\u00e9ologico-politique par Spinoza en CPGE fran\u00e7ais sur le th\u00e8me individu et communaut\u00e9","og_url":"https:\/\/groupe-reussite.fr\/ressources\/cp-francais-spinoza-prepa-analyse\/","og_site_name":"Groupe R\u00e9ussite","article_publisher":"https:\/\/www.facebook.com\/GroupeReussiteOfficiel\/","article_modified_time":"2024-11-14T12:21:04+00:00","og_image":[{"url":"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2020\/03\/cours-particuliers.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@GroupeReussite","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/groupe-reussite.fr\/ressources\/cp-francais-spinoza-prepa-analyse\/","url":"https:\/\/groupe-reussite.fr\/ressources\/cp-francais-spinoza-prepa-analyse\/","name":"Spinoza CPGE fran\u00e7ais : R\u00e9sum\u00e9 du Trait\u00e9 th\u00e9ologico-politique","isPartOf":{"@id":"https:\/\/groupe-reussite.fr\/ressources\/#website"},"primaryImageOfPage":{"@id":"https:\/\/groupe-reussite.fr\/ressources\/cp-francais-spinoza-prepa-analyse\/#primaryimage"},"image":{"@id":"https:\/\/groupe-reussite.fr\/ressources\/cp-francais-spinoza-prepa-analyse\/#primaryimage"},"thumbnailUrl":"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2020\/03\/cours-particuliers.jpg","datePublished":"2024-08-02T15:54:53+00:00","dateModified":"2024-11-14T12:21:04+00:00","description":"Analyse d\u00e9taill\u00e9e du Trait\u00e9 th\u00e9ologico-politique par Spinoza en CPGE fran\u00e7ais sur le th\u00e8me individu et communaut\u00e9","breadcrumb":{"@id":"https:\/\/groupe-reussite.fr\/ressources\/cp-francais-spinoza-prepa-analyse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/groupe-reussite.fr\/ressources\/cp-francais-spinoza-prepa-analyse\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/groupe-reussite.fr\/ressources\/cp-francais-spinoza-prepa-analyse\/#primaryimage","url":"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2020\/03\/cours-particuliers.jpg","contentUrl":"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2020\/03\/cours-particuliers.jpg","width":300,"height":210,"caption":"cours-particulier-paris"},{"@type":"BreadcrumbList","@id":"https:\/\/groupe-reussite.fr\/ressources\/cp-francais-spinoza-prepa-analyse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/groupe-reussite.fr\/ressources\/"},{"@type":"ListItem","position":2,"name":"R\u00e9sum\u00e9 analyse Spinoza"}]},{"@type":"WebSite","@id":"https:\/\/groupe-reussite.fr\/ressources\/#website","url":"https:\/\/groupe-reussite.fr\/ressources\/","name":"Groupe R\u00e9ussite - Cours particuliers et stages de vacances","description":"Stage et Cours particuliers maths, fran\u00e7ais, anglais, informatique, physique chimie","publisher":{"@id":"https:\/\/groupe-reussite.fr\/ressources\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/groupe-reussite.fr\/ressources\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/groupe-reussite.fr\/ressources\/#organization","name":"Groupe R\u00e9ussite - Cours particuliers et stages de vacances","url":"https:\/\/groupe-reussite.fr\/ressources\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/groupe-reussite.fr\/ressources\/#\/schema\/logo\/image\/","url":"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2026\/05\/logo-groupe-reussite-carre.png","contentUrl":"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2026\/05\/logo-groupe-reussite-carre.png","width":170,"height":180,"caption":"Groupe R\u00e9ussite - Cours particuliers et stages de vacances"},"image":{"@id":"https:\/\/groupe-reussite.fr\/ressources\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GroupeReussiteOfficiel\/","https:\/\/x.com\/GroupeReussite","https:\/\/www.youtube.com\/c\/GroupeReussite","https:\/\/www.instagram.com\/groupe_reussite_officiel\/","https:\/\/fr.linkedin.com\/company\/groupe-reussite","https:\/\/www.tiktok.com\/@groupereussite","https:\/\/fr.pinterest.com\/GroupeReussite\/","https:\/\/www.reddit.com\/user\/Groupe-Reussite\/"]}]}},"_links":{"self":[{"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/pages\/213989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/users\/81"}],"replies":[{"embeddable":true,"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/comments?post=213989"}],"version-history":[{"count":3,"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/pages\/213989\/revisions"}],"predecessor-version":[{"id":220470,"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/pages\/213989\/revisions\/220470"}],"wp:attachment":[{"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/media?parent=213989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}