{"id":74388,"date":"2020-11-09T17:24:23","date_gmt":"2020-11-09T16:24:23","guid":{"rendered":"https:\/\/groupe-reussite.fr\/?page_id=74388"},"modified":"2023-10-12T14:14:11","modified_gmt":"2023-10-12T13:14:11","slug":"cours-en-ligne-premiere-roman","status":"publish","type":"page","link":"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-roman\/","title":{"rendered":"Cours sur le roman en premi\u00e8re"},"content":{"rendered":"<div class=\"Latex_page\">\n<section class=\"has_ae_slider elementor-element elementor-section-full_width elementor-reverse-mobile elementor-section-stretched elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default elementor-section elementor-top-section\">\n<div class=\"elementor-container elementor-column-gap-no\">\n<div class=\"elementor-row\">\n<div class=\"elementor-column-wrap elementor-element-populated colone_elementor\">\n<p style=\"text-align: justify\">\t\t<div data-elementor-type=\"page\" data-elementor-id=\"87193\" class=\"elementor elementor-87193\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-484acd1c elementor-section-content-bottom elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"484acd1c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2fc4bd91 sticky_badeau_colone strick_col ae-bg-gallery-type-default\" data-id=\"2fc4bd91\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-2f443b98 elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"2f443b98\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2925015e strick_col ae-bg-gallery-type-default\" data-id=\"2925015e\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6958a8c6 elementor-widget elementor-widget-heading\" data-id=\"6958a8c6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-francais-premiere\/\">Cours en ligne Fran\u00e7ais en Premi\u00e8re<\/a><\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7360fde6 elementor-widget elementor-widget-heading\" data-id=\"7360fde6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Chapitres Fran\u00e7ais en Premi\u00e8re<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73b53a1b elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"73b53a1b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-mouvements-litteraires\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Mouvements Litt\u00e9raires<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bf5908e elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"5bf5908e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-registres-litteraires\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Registres Litt\u00e9raires<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79c220dd elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"79c220dd\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Genres Litt\u00e9raires<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e491126 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"1e491126\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-poesie\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Cours sur la Po\u00e9sie<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54ba967c elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"54ba967c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Mouvements et Formes Po\u00e9tiques au XIX et XX<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c48385e elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"4c48385e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Analyse Texte Po\u00e9tique<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f4a2430 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"1f4a2430\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-contemplations-hugo\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Fiche de Lecture, Les Contemplations V.Hugo<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-789a44fa elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"789a44fa\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-fleurs-du-mal\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Fiche de Lecture, Les fleurs du mal, C.Baudelaire<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b8a4c7e elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"1b8a4c7e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-alcools-apollinaire\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Fiche de Lecture, Alcools, G.Apollinaire<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcb202d elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"bcb202d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-exercices-corriges-commentaire-lenterrement-verlaine\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Commentaire Corrig\u00e9, L'enterrement, P.Verlaine<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b3eece2 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"7b3eece2\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Histoire de la Litt\u00e9rature d'id\u00e9es<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72a9e9ca elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"72a9e9ca\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Formes Argumentatives<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bafdcd0 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"3bafdcd0\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Analyse Texte Argumentatif<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c75ff97 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"3c75ff97\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-declaration-droits-femme-citoyenne\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Fiche de Lecture, Olympe de Gouges<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5975d5c6 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"5975d5c6\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-roman\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Histoire du Roman<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66d7deb3 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"66d7deb3\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Les Genres du R\u00e9cit<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b00ac43 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"6b00ac43\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Analyse Texte Narratif<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52a817d3 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"52a817d3\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-princesse-de-cleves-lafayette\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Fiche de Lecture, La princesse de Cl\u00e8ves, Mme Lafayette<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-312d75cd elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"312d75cd\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-le-rouge-et-le-noir-stendhal\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Fiche de Lecture, Le rouge et le noir, Stendhal<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67b09cdb elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"67b09cdb\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-memoires-hadrien-yourcenar\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Fiche de Lecture, M\u00e9moires d'Hadrien, M.Yourcenar<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41c04fce elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"41c04fce\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-theatre\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Histoire et Genres du Th\u00e9\u00e2tre<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fa9980c elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"2fa9980c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-juste-la-fin-du-monde-lagarce\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Fiche de Lecture, Juste la fin du monde, Lagarce<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43989bf8 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"43989bf8\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-le-malade-imaginaire-moliere\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Fiche de Lecture, Le malade imaginaire, Moli\u00e8re<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31949308 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"31949308\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-fausses-confidences-marivaux\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Fiche de Lecture, Les fausses confidences, Marivaux<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c36f0bd elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"4c36f0bd\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-methode-commentaire-litteraire\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Le Commentaire Litt\u00e9raire<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4611efbe elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"4611efbe\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">La Dissertation<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-718b5c5 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"718b5c5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-outils-formules-redaction\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Orthographe et R\u00e9daction<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c8742b elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"2c8742b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-interrogation-grammaire\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">L'interrogation<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-380255d elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"380255d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-valeur-temps-et-modes-grammaire\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">La valeur des temps et des modes<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb4e226 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"bb4e226\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-conseils-oral-bac-francais\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Conseils Oral Bac de Fran\u00e7ais<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3142307d elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"3142307d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/nous-contacter\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">CONTACTEZ-NOUS<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-39df2f8 elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"39df2f8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-127a743 ae-bg-gallery-type-default\" data-id=\"127a743\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n<div class=\"elementor-column-wrap elementor-element-populated colone_latex\">\n<div class=\"style_pag\" style=\"color: #000;font-family: 'Lato', Sans-serif\">\n<div class=\"elementor-text-editor elementor-clearfix\" style=\"color: #000000;font-family: Lato, sans-serif;text-align: justify\">\n<h1 class=\"Latex_page_title\" style=\"text-align: center\">Cours sur le roman au bac de fran\u00e7ais<\/h1>\n<\/div>\n<p class=\"colone_latex_ancres\" style=\"color: #000000;font-family: Lato, sans-serif;text-align: center\"><a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-roman\/\">R\u00e9sum\u00e9 de cours<\/a>\u00a0 <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-exercices-corriges-roman\/\">Exercices et corrig\u00e9s<\/a><\/p>\n<p class=\"colone_latex_ancres\" style=\"color: #000000;font-family: Lato, sans-serif;text-align: center\"><a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-francais-premiere\/\">Cours en ligne de Fran\u00e7ais en Premi\u00e8re<\/a><\/p>\n<p style=\"text-align: justify\">Ce <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-francais-premiere\/\">cours en ligne de fran\u00e7ais en premi\u00e8re<\/a> sur le <strong>roman au bac de fran\u00e7ais<\/strong> est utile pour les \u00e9l\u00e8ves souhaitant r\u00e9viser ce chapitre du programme car le roman est l&rsquo;un des th\u00e8mes inclus dans la pr\u00e9paration du bac de fran\u00e7ais, en plus d&rsquo;autres th\u00e8mes comme la <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-poesie\/\">po\u00e9sie<\/a> ou le <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-theatre\/\">th\u00e9\u00e2tre<\/a>. Pour renforcer vos chances de r\u00e9ussite au bac de fran\u00e7ais, vous pouvez faire appel \u00e0 un <a href=\"https:\/\/groupe-reussite.fr\/cours-particuliers\/francais\/tous-niveaux\/france\/\">professeur de fran\u00e7ais particulier<\/a>. Il vous dispensera des cours de fran\u00e7ais personnalis\u00e9s r\u00e9pondant \u00e0 vos besoins en termes de pr\u00e9paration au bac.<\/p>\n<h2 style=\"text-align: justify\">D\u00e9finition d&rsquo;un roman<\/h2>\n<p style=\"text-align: justify\">Le <strong>roman<\/strong> peut se d\u00e9finir comme une \u00ab \u0152uvre litt\u00e9raire en prose d&rsquo;une certaine longueur, m\u00ealant le r\u00e9el et l&rsquo;imaginaire, et qui, dans sa forme la plus traditionnelle, cherche \u00e0 susciter l&rsquo;int\u00e9r\u00eat, le plaisir du lecteur en racontant le destin d&rsquo;un h\u00e9ros principal, une intrigue entre plusieurs personnages, pr\u00e9sent\u00e9s dans leur psychologie, leurs passions, leurs aventures, leur milieu social, sur un arri\u00e8re-fond moral, m\u00e9taphysique; genre litt\u00e9raire regroupant toutes les vari\u00e9t\u00e9s de ces \u0153uvres, particuli\u00e8rement florissant au XIXe s. \u00c0 l&rsquo;origine, \u0153uvre narrative en prose ou en vers, \u00e9crite en langue romane (le Roman de la Rose, le Roman de Renart, par exemple), d&rsquo;o\u00f9 le nom donn\u00e9 au genre. \u00bb (TLF) (Attention \u00e0 ne pas confondre <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-mouvements-litteraires\/\">mouvement litt\u00e9raire<\/a>, genre et <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-registres-litteraires\/\">registre litt\u00e9raire<\/a>).<\/p>\n<p data-pm-slice=\"1 1 []\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"190573\" class=\"elementor elementor-190573\">\n\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-inner-section elementor-element elementor-element-7f0071b3 elementor-section-content-bottom full_width elementor-section-full_width elementor-section-height-min-height elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"7f0071b3\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-6849d5da ae-bg-gallery-type-default\" data-id=\"6849d5da\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-311d1d62 elementor-widget elementor-widget-heading\" data-id=\"311d1d62\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">TROUVEZ LE MEILLEUR ENSEIGNANT<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14c2df17 elementor-widget elementor-widget-heading\" data-id=\"14c2df17\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">P\u00e9dagogie, bienveillance et suivi<br\/> Profs certifi\u00e9s et agr\u00e9g\u00e9s <\/b><\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-229e3a7 elementor-widget elementor-widget-heading\" data-id=\"229e3a7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Contactez Groupe R\u00e9ussite<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a0746c elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"9a0746c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/cours-particuliers\/francais\/tous-niveaux\/france\/\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\" id=\"CTA_PRD_CP\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Cours particuliers fran\u00e7ais<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-796183a9 elementor-widget elementor-widget-text-editor\" data-id=\"796183a9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: left;\"><b>Avis Google France <\/b><span style=\"color: #e5a430;\"><b>\u2605\u2605\u2605\u2605\u2605<\/b><\/span><b> 4,9 sur 5<\/b><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-26ffe18b ae-bg-gallery-type-default\" data-id=\"26ffe18b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify\">Histoire du roman<\/h2>\n<p style=\"text-align: justify\">Le <strong>roman<\/strong> existe d\u00e9j\u00e0 dans l&rsquo;Antiquit\u00e9 grecque (Daphnis et Chlo\u00e9, Longus) et romaine (Satyricon, P\u00e9trone). Il se d\u00e9veloppe au Moyen-Age, en langue romane, donc vernaculaire, en marge des chansons de geste en vers et des r\u00e9cits de vies de saints en latin.<\/p>\n<p style=\"text-align: justify\">Le <strong>roman<\/strong> a longtemps \u00e9t\u00e9 consid\u00e9r\u00e9 comme un genre secondaire, car peu d\u00e9velopp\u00e9 durant l&rsquo;Antiquit\u00e9 et remis en question par l\u2019\u00c9glise comme immoral. Il trouve ses lettres de noblesse au XIXe si\u00e8cle. Le roman dans sa conception classique sera remis en cause par les auteurs du Nouveau roman (refus d&rsquo;une intrigue, d&rsquo;une avanc\u00e9e chronologique, et autres codes romanesques traditionnels \u00e0 l&rsquo;aune d&rsquo;une perception nouvelle de l&rsquo;individu).<\/p>\n<h2 style=\"text-align: justify\">Genres de romans<\/h2>\n<p style=\"text-align: justify\">On trouve diff\u00e9rents <strong>genres de roman<\/strong>, par exemple :<\/p>\n<ul style=\"text-align: justify\">\n<li>Le <strong>roman \u00e9pistolaire<\/strong> : roman par lettres, comme<em> Les Liaisons dangereuses<\/em> de Choderlos de Laclos. Le roman \u00e9pistolaire permet de multiplier les points de vue sur un \u00e9v\u00e9nement (plusieurs personnages \u00e9crivent sur un \u00e9v\u00e9nement et en donnent leur compr\u00e9hension), et de faire appel \u00e0 diff\u00e9rents tons (tous les personnages n&rsquo;\u00e9crivent pas de la m\u00eame mani\u00e8re).<\/li>\n<li>Le<strong> roman d&rsquo;apprentissage<\/strong> : roman qui relate \u00ab l&rsquo;apprentissage \u00bb social, moral, amoureux, d&rsquo;un personnage, comme Julien dans <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-le-rouge-et-le-noir-stendhal\/\"><em>Le Rouge et le Noir<\/em> de Stendhal<\/a>.<\/li>\n<li>Le<strong> roman historique<\/strong> : il cherche \u00e0 donner une lecture d&rsquo;une p\u00e9riode\/ d&rsquo;un \u00e9v\u00e9nement historique par le biais de la fiction romanesque. On peut penser \u00e0 <em>La Reine Margot<\/em> de Dumas.<\/li>\n<li>Le <strong>roman autobiographique<\/strong> : il ne s&rsquo;agit pas d&rsquo;une autobiographie, mais d&rsquo;un roman dont l&rsquo;intrigue se base sur des \u00e9l\u00e9ments autobiographiques tout en restant un roman (il n&rsquo;a pas pour but de peindre fid\u00e8lement l&rsquo;auteur). On peut penser \u00e0 <em>Voyage au bout de la nuit<\/em> de C\u00e9line.<\/li>\n<\/ul>\n<p style=\"text-align: justify\">Il existe une multitude de<strong> types de romans<\/strong>, je n&rsquo;en \u00e9voque ici que quelques uns (on peut encore penser au roman d&rsquo;aventure, au roman policier, etc.).<\/p>\n<h2 style=\"text-align: justify\">Questions romanesques<\/h2>\n<p style=\"text-align: justify\">Qu&rsquo;\u00e9tudier dans un <strong>roman<\/strong> ? A quoi dont-on s&rsquo;int\u00e9resser lorsqu&rsquo;on en analyse un extrait ou qu&rsquo;on l&rsquo;\u00e9voque dans une dissertation ? Voici quelques pistes.<\/p>\n<p style=\"text-align: justify\"><strong>A) La narration<\/strong><\/p>\n<p style=\"text-align: justify\">Dans un roman, on distingue le narrateur de l\u2019auteur : le narrateur est celui qui raconte l\u2019histoire, l\u2019auteur est celui qui l\u2019\u00e9crit, c\u2019est-\u00e0-dire une personne r\u00e9elle. Il s&rsquo;agit de se demander ici \u00ab Qui parle ? \u00bb.<\/p>\n<p style=\"text-align: justify\">On distingue plusieurs types de narrateur :<\/p>\n<ul style=\"text-align: justify\">\n<li>Le narrateur h\u00e9t\u00e9rodi\u00e9g\u00e9tique : il est ext\u00e9rieur \u00e0 la fiction, ce n\u2019est pas un personnage du roman. Il peut \u00eatre omniscient (il sait tout : les motivations des personnages, cach\u00e9es, leurs sentiments les uns vis \u00e0 vis des autres, leur avenir, leur pass\u00e9, etc.)<\/li>\n<li>Le narrateur homodi\u00e9g\u00e9tique : la narration est assur\u00e9e par un personnage de la fiction, c&rsquo;est lui qui raconte l&rsquo;histoire.<\/li>\n<\/ul>\n<p style=\"text-align: justify\">Une notion essentielle est \u00e9galement celle du \u00ab point de vue \u00bb du narrateur (on parle de focalisation) : il s&rsquo;agit ici de se demander \u00ab Qui voit ? \u00bb.<\/p>\n<p style=\"text-align: justify\">On distingue plusieurs focalisations dans un <strong>roman<\/strong> :<\/p>\n<ul style=\"text-align: justify\">\n<li>La focalisation z\u00e9ro : le narrateur est omniscient (il voit tout, sait tout sur les personnages, leurs actions, leurs pens\u00e9es : rien n\u2019est cach\u00e9 au narrateur et donc au lecteur)<\/li>\n<li>La focalisation interne : le narrateur prend le point de vue d\u2019un personnage du roman, c&rsquo;est lui qui voit et on voit par lui.<\/li>\n<li>La focalisation externe : le narrateur, un personnage ext\u00e9rieur au r\u00e9cit, relate seulement ce qu\u2019il voit : la vision est tronqu\u00e9e, minimale.<\/li>\n<\/ul>\n<p style=\"text-align: justify\">Dans un <strong>roman<\/strong>, les points de vue peuvent changer selon les chapitres, les passages.<\/p>\n<p>&nbsp;<\/p>\n\t\t<div data-elementor-type=\"section\" data-elementor-id=\"127774\" class=\"elementor elementor-127774\">\n\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-inner-section elementor-element elementor-element-5a7b6a2a elementor-section-content-bottom full_width elementor-section-full_width elementor-section-height-min-height elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"5a7b6a2a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-749af387 ae-bg-gallery-type-default\" data-id=\"749af387\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b4ed465 elementor-widget elementor-widget-heading\" data-id=\"1b4ed465\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">COURS PARTICULIERS EN LIGNE<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16d47760 elementor-widget elementor-widget-heading\" data-id=\"16d47760\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Nous avons s\u00e9lectionn\u00e9 pour vous les meilleurs professeurs particuliers.<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21a162bf elementor-widget elementor-widget-heading\" data-id=\"21a162bf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">POUR ACC\u00c9L\u00c9RER MA PROGRESSION<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5600477e elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"5600477e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/cours-en-ligne\/toutes-matieres\/tous-niveaux\/france\/\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\" id=\"CTA_PRD_CP\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Cours particuliers en ligne<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c7a7876 elementor-widget elementor-widget-text-editor\" data-id=\"1c7a7876\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: left;\"><b>Avis Google France <\/b><span style=\"color: #e5a430;\"><b>\u2605\u2605\u2605\u2605\u2605<\/b><\/span><b> 4,9 sur 5<\/b><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2aa12288 ae-bg-gallery-type-default\" data-id=\"2aa12288\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\">La suite du cours sur le <strong>roman en 1\u00e8re <\/strong>est disponible sur l&rsquo;application mobile PrepApp. Afin d&rsquo;approfondir ce cours sur le <strong>roman<\/strong>, les \u00e9l\u00e8ves peuvent aussi prendre des cours particuliers de fran\u00e7ais, notamment pour acqu\u00e9rir la <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-methode-commentaire-litteraire\/\">m\u00e9thodologie du commentaire litt\u00e9raire<\/a> et de la dissertation et conna\u00eetre les <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-outils-formules-redaction\/\">outils et formules pour la r\u00e9daction au bac de fran\u00e7ais<\/a> ainsi que les <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-conseils-oral-bac-francais\/\">conseils pour l&rsquo;oral du bac de fran\u00e7ais<\/a>.<\/p>\n<p>Des cours sont \u00e9galement disponibles pour les \u00e9l\u00e8ves souhaitant r\u00e9viser les \u0153uvres au programme du bac de fran\u00e7ais :<\/p>\n<ul>\n<li>les <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-contemplations-hugo\/\">Contemplations de Victor Hugo<\/a><\/li>\n<li>les <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-fleurs-du-mal\/\">Fleurs du mal de Baudelaire<\/a><\/li>\n<li><a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-alcools-apollinaire\/\">Alcools d&rsquo;Apollinaire<\/a><\/li>\n<li>l&rsquo;<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-exercices-corriges-commentaire-lenterrement-verlaine\/\">Enterrement de Paul Verlaine<\/a><\/li>\n<li>les <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-lettres-persanes\/\">Lettres Persanes de Montesquieu<\/a><\/li>\n<li>les <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-memoires-hadrien-yourcenar\/\">M\u00e9moires d&rsquo;Hadrien de Yourcenar<\/a><\/li>\n<li>les <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-fables-la-fontaine\/\">Fables de la Fontaine<\/a><\/li>\n<li><a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-le-malade-imaginaire-moliere\/\">le Malade Imaginaire de Moli\u00e8re<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cours sur le roman au bac de fran\u00e7ais R\u00e9sum\u00e9 de cours\u00a0 Exercices et corrig\u00e9s Cours en ligne de Fran\u00e7ais en Premi\u00e8re Ce cours en ligne de fran\u00e7ais en premi\u00e8re sur le roman au bac de fran\u00e7ais est utile pour les \u00e9l\u00e8ves souhaitant r\u00e9viser ce chapitre du programme car le roman est l&rsquo;un des th\u00e8mes inclus [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.2.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le roman au bac de fran\u00e7ais : cours en ligne gratuit<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez notre cours en ligne sur le roman au bac de fran\u00e7ais : histoire du roman, genres de roman, questions romanesques...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-roman\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le roman au bac de fran\u00e7ais : cours en ligne gratuit\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez notre cours en ligne sur le roman au bac de fran\u00e7ais : histoire du roman, genres de roman, questions romanesques...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-roman\/\" \/>\n<meta property=\"og:site_name\" content=\"Groupe R\u00e9ussite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GroupeReussiteOfficiel\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-12T13:14:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2026\/05\/logo-groupe-reussite-carre.png\" \/>\n\t<meta property=\"og:image:width\" content=\"170\" \/>\n\t<meta property=\"og:image:height\" content=\"180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@GroupeReussite\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-roman\/\",\"url\":\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-roman\/\",\"name\":\"Le roman au bac de fran\u00e7ais : cours en ligne gratuit\",\"isPartOf\":{\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/#website\"},\"datePublished\":\"2020-11-09T16:24:23+00:00\",\"dateModified\":\"2023-10-12T13:14:11+00:00\",\"description\":\"D\u00e9couvrez notre cours en ligne sur le roman au bac de fran\u00e7ais : histoire du roman, genres de roman, questions romanesques...\",\"breadcrumb\":{\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-roman\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-roman\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-roman\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/groupe-reussite.fr\/ressources\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cours sur le roman en premi\u00e8re\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/#website\",\"url\":\"https:\/\/groupe-reussite.fr\/ressources\/\",\"name\":\"Groupe R\u00e9ussite - Cours particuliers et stages de vacances\",\"description\":\"Stage et Cours particuliers maths, fran\u00e7ais, anglais, informatique, physique chimie\",\"publisher\":{\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/groupe-reussite.fr\/ressources\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/#organization\",\"name\":\"Groupe R\u00e9ussite - Cours particuliers et stages de vacances\",\"url\":\"https:\/\/groupe-reussite.fr\/ressources\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2026\/05\/logo-groupe-reussite-carre.png\",\"contentUrl\":\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2026\/05\/logo-groupe-reussite-carre.png\",\"width\":170,\"height\":180,\"caption\":\"Groupe R\u00e9ussite - Cours particuliers et stages de vacances\"},\"image\":{\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/GroupeReussiteOfficiel\/\",\"https:\/\/twitter.com\/GroupeReussite\",\"https:\/\/www.youtube.com\/c\/GroupeReussite\",\"https:\/\/www.instagram.com\/groupe_reussite_officiel\/\",\"https:\/\/fr.linkedin.com\/company\/groupe-reussite\",\"https:\/\/www.tiktok.com\/@groupereussite\",\"https:\/\/fr.pinterest.com\/GroupeReussite\/\",\"https:\/\/www.reddit.com\/user\/Groupe-Reussite\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le roman au bac de fran\u00e7ais : cours en ligne gratuit","description":"D\u00e9couvrez notre cours en ligne sur le roman au bac de fran\u00e7ais : histoire du roman, genres de roman, questions romanesques...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-roman\/","og_locale":"fr_FR","og_type":"article","og_title":"Le roman au bac de fran\u00e7ais : cours en ligne gratuit","og_description":"D\u00e9couvrez notre cours en ligne sur le roman au bac de fran\u00e7ais : histoire du roman, genres de roman, questions romanesques...","og_url":"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-roman\/","og_site_name":"Groupe R\u00e9ussite","article_publisher":"https:\/\/www.facebook.com\/GroupeReussiteOfficiel\/","article_modified_time":"2023-10-12T13:14:11+00:00","og_image":[{"width":170,"height":180,"url":"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2026\/05\/logo-groupe-reussite-carre.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@GroupeReussite","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-roman\/","url":"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-roman\/","name":"Le roman au bac de fran\u00e7ais : cours en ligne gratuit","isPartOf":{"@id":"https:\/\/groupe-reussite.fr\/ressources\/#website"},"datePublished":"2020-11-09T16:24:23+00:00","dateModified":"2023-10-12T13:14:11+00:00","description":"D\u00e9couvrez notre cours en ligne sur le roman au bac de fran\u00e7ais : histoire du roman, genres de roman, questions romanesques...","breadcrumb":{"@id":"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-roman\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-roman\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-roman\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/groupe-reussite.fr\/ressources\/"},{"@type":"ListItem","position":2,"name":"Cours sur le roman en premi\u00e8re"}]},{"@type":"WebSite","@id":"https:\/\/groupe-reussite.fr\/ressources\/#website","url":"https:\/\/groupe-reussite.fr\/ressources\/","name":"Groupe R\u00e9ussite - Cours particuliers et stages de vacances","description":"Stage et Cours particuliers maths, fran\u00e7ais, anglais, informatique, physique chimie","publisher":{"@id":"https:\/\/groupe-reussite.fr\/ressources\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/groupe-reussite.fr\/ressources\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/groupe-reussite.fr\/ressources\/#organization","name":"Groupe R\u00e9ussite - Cours particuliers et stages de vacances","url":"https:\/\/groupe-reussite.fr\/ressources\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/groupe-reussite.fr\/ressources\/#\/schema\/logo\/image\/","url":"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2026\/05\/logo-groupe-reussite-carre.png","contentUrl":"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2026\/05\/logo-groupe-reussite-carre.png","width":170,"height":180,"caption":"Groupe R\u00e9ussite - Cours particuliers et stages de vacances"},"image":{"@id":"https:\/\/groupe-reussite.fr\/ressources\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GroupeReussiteOfficiel\/","https:\/\/twitter.com\/GroupeReussite","https:\/\/www.youtube.com\/c\/GroupeReussite","https:\/\/www.instagram.com\/groupe_reussite_officiel\/","https:\/\/fr.linkedin.com\/company\/groupe-reussite","https:\/\/www.tiktok.com\/@groupereussite","https:\/\/fr.pinterest.com\/GroupeReussite\/","https:\/\/www.reddit.com\/user\/Groupe-Reussite\/"]}]}},"_links":{"self":[{"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/pages\/74388"}],"collection":[{"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/comments?post=74388"}],"version-history":[{"count":2,"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/pages\/74388\/revisions"}],"predecessor-version":[{"id":191763,"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/pages\/74388\/revisions\/191763"}],"wp:attachment":[{"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/media?parent=74388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}