{"id":75668,"date":"2020-11-13T11:10:49","date_gmt":"2020-11-13T10:10:49","guid":{"rendered":"https:\/\/groupe-reussite.fr\/?page_id=75668"},"modified":"2023-10-12T13:35:44","modified_gmt":"2023-10-12T12:35:44","slug":"cours-en-ligne-premiere-registres-litteraires","status":"publish","type":"page","link":"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-registres-litteraires\/","title":{"rendered":"Cours sur les registres litt\u00e9raires"},"content":{"rendered":"<div class=\"Latex_page\">\n<section class=\"has_ae_slider elementor-element elementor-section-full_width elementor-reverse-mobile elementor-section-stretched elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default elementor-section elementor-top-section\">\n<div class=\"elementor-container elementor-column-gap-no\">\n<div class=\"elementor-row\">\n<div class=\"elementor-column-wrap elementor-element-populated colone_elementor\">\n<p style=\"text-align: justify\">\t\t<div data-elementor-type=\"page\" data-elementor-id=\"87193\" class=\"elementor elementor-87193\">\n\t\t\t\t\t\t<div class=\"elementor-inner\">\n\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-484acd1c elementor-section-content-bottom elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"484acd1c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2fc4bd91 sticky_badeau_colone strick_col ae-bg-gallery-type-default\" data-id=\"2fc4bd91\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-2f443b98 elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"2f443b98\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2925015e strick_col ae-bg-gallery-type-default\" data-id=\"2925015e\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6958a8c6 elementor-widget elementor-widget-heading\" data-id=\"6958a8c6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-francais-premiere\/\">Cours en ligne Fran\u00e7ais en Premi\u00e8re<\/a><\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7360fde6 elementor-widget elementor-widget-heading\" data-id=\"7360fde6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Chapitres Fran\u00e7ais en Premi\u00e8re<\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73b53a1b elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"73b53a1b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-mouvements-litteraires\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Mouvements Litt\u00e9raires<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bf5908e elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"5bf5908e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-registres-litteraires\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Registres Litt\u00e9raires<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79c220dd elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"79c220dd\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Genres Litt\u00e9raires<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e491126 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"1e491126\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-poesie\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Cours sur la Po\u00e9sie<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54ba967c elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"54ba967c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Mouvements et Formes Po\u00e9tiques au XIX et XX<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c48385e elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"4c48385e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Analyse Texte Po\u00e9tique<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f4a2430 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"1f4a2430\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-contemplations-hugo\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Fiche de Lecture, Les Contemplations V.Hugo<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-789a44fa elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"789a44fa\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-fleurs-du-mal\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Fiche de Lecture, Les fleurs du mal, C.Baudelaire<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b8a4c7e elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"1b8a4c7e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-alcools-apollinaire\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Fiche de Lecture, Alcools, G.Apollinaire<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bcb202d elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"bcb202d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-exercices-corriges-commentaire-lenterrement-verlaine\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Commentaire Corrig\u00e9, L'enterrement, P.Verlaine<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b3eece2 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"7b3eece2\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Histoire de la Litt\u00e9rature d'id\u00e9es<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72a9e9ca elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"72a9e9ca\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Formes Argumentatives<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bafdcd0 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"3bafdcd0\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Analyse Texte Argumentatif<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c75ff97 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"3c75ff97\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-declaration-droits-femme-citoyenne\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Fiche de Lecture, Olympe de Gouges<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5975d5c6 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"5975d5c6\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-roman\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Histoire du Roman<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-66d7deb3 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"66d7deb3\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Les Genres du R\u00e9cit<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b00ac43 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"6b00ac43\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Analyse Texte Narratif<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52a817d3 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"52a817d3\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-princesse-de-cleves-lafayette\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Fiche de Lecture, La princesse de Cl\u00e8ves, Mme Lafayette<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-312d75cd elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"312d75cd\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-le-rouge-et-le-noir-stendhal\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Fiche de Lecture, Le rouge et le noir, Stendhal<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67b09cdb elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"67b09cdb\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-memoires-hadrien-yourcenar\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Fiche de Lecture, M\u00e9moires d'Hadrien, M.Yourcenar<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-41c04fce elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"41c04fce\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-theatre\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Histoire et Genres du Th\u00e9\u00e2tre<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fa9980c elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"2fa9980c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-juste-la-fin-du-monde-lagarce\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Fiche de Lecture, Juste la fin du monde, Lagarce<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43989bf8 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"43989bf8\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-le-malade-imaginaire-moliere\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Fiche de Lecture, Le malade imaginaire, Moli\u00e8re<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31949308 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"31949308\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-fausses-confidences-marivaux\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Fiche de Lecture, Les fausses confidences, Marivaux<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4c36f0bd elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"4c36f0bd\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-methode-commentaire-litteraire\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Le Commentaire Litt\u00e9raire<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4611efbe elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"4611efbe\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">La Dissertation<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-718b5c5 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"718b5c5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-outils-formules-redaction\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Orthographe et R\u00e9daction<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c8742b elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"2c8742b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-interrogation-grammaire\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">L'interrogation<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-380255d elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"380255d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-valeur-temps-et-modes-grammaire\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">La valeur des temps et des modes<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb4e226 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"bb4e226\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-conseils-oral-bac-francais\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Conseils Oral Bac de Fran\u00e7ais<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3142307d elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"3142307d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/nous-contacter\/\" class=\"elementor-button-link elementor-button elementor-size-sm\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">CONTACTEZ-NOUS<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-top-section elementor-element elementor-element-39df2f8 elementor-section-boxed elementor-section-height-default elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"39df2f8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-127a743 ae-bg-gallery-type-default\" data-id=\"127a743\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\n<\/div>\n<div class=\"elementor-column-wrap elementor-element-populated colone_latex\">\n<div class=\"style_pag\" style=\"color: #000;font-family: 'Lato', Sans-serif\">\n<div class=\"elementor-text-editor elementor-clearfix\" style=\"color: #000000;font-family: Lato, sans-serif;text-align: justify\">\n<h1 class=\"Latex_page_title\" style=\"text-align: center\">Les registres litt\u00e9raires<\/h1>\n<\/div>\n<p class=\"colone_latex_ancres\" style=\"color: #000000;font-family: Lato, sans-serif;text-align: center\"><a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-registres-litteraires\/\">R\u00e9sum\u00e9 de cours<\/a> <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-exercices-corriges-registres-litteraires\/\">Exercices et corrig\u00e9s<\/a><\/p>\n<p class=\"colone_latex_ancres\" style=\"color: #000000;font-family: Lato, sans-serif;text-align: center\"><a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-francais-premiere\/\">Cours en ligne de Fran\u00e7ais en Premi\u00e8re<\/a><\/p>\n<p style=\"text-align: justify\">Le <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-francais-premiere\/\">cours en ligne de fran\u00e7ais en premi\u00e8re<\/a> sur les <strong>registres litt\u00e9raires<\/strong> est indispensable \u00e0 conna\u00eetre car les registres litt\u00e9raires permettent de comprendre et d&rsquo;analyser une \u0153uvre litt\u00e9raire. Ce cours est donc essentiel \u00e0 conna\u00eetre afin de pr\u00e9parer le bac de fran\u00e7ais. Les \u00e9l\u00e8ves peuvent aussi consulter notre cours sur les <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-outils-formules-redaction\/\">outils et formules pour la r\u00e9daction au bac de fran\u00e7ais<\/a> ainsi que nos <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-conseils-oral-bac-francais\/\">conseils pour l&rsquo;oral du bac de fran\u00e7ais<\/a>. Pour renforcer davantage votre pr\u00e9paration au bac, et notamment aux registres litt\u00e9raires, nous vous invitons \u00e0 prendre un <a href=\"https:\/\/groupe-reussite.fr\/cours-particuliers\/francais\/tous-niveaux\/france\/\">cours de fran\u00e7ais \u00e0 domicile<\/a> avec l&rsquo;un de nos professeurs particuliers agr\u00e9g\u00e9s. Vous serez ainsi totalement pr\u00e9par\u00e9s \u00e0 l&rsquo;\u00e9preuve de fran\u00e7ais au bac.<\/p>\n<h2 style=\"text-align: justify\">Qu&rsquo;est-ce qu&rsquo;un registre litt\u00e9raire ?<\/h2>\n<p style=\"text-align: justify\">Un <strong>registre litt\u00e9raire<\/strong> traduit la tonalit\u00e9 d\u2019un texte, son ton, qui vise \u00e0 produire un effet sur le lecteur. Pour ce faire, l\u2019auteur va faire en sorte de traduire, dans son \u00e9crit, une certaine vision des situations et du monde, un point de vue particulier sur des \u00e9v\u00e9nements, une repr\u00e9sentation sous un angle particulier. Attention \u00e0 ne pas confondre registre et <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-mouvements-litteraires\/\">mouvement litt\u00e9raire<\/a> !<\/p>\n<p style=\"text-align: justify\">Ainsi si un texte a pour but de faire rire, le <strong>registre litt\u00e9raire<\/strong> sera comique en r\u00e9v\u00e9lant le c\u00f4t\u00e9 humoristique d\u2019une situation. Si un texte a pour but de faire na\u00eetre de la piti\u00e9, de la tristesse ou de la compassion chez un lecteur, on dira que le registre est \u00ab path\u00e9tique \u00bb. Si un texte a pour but de donner l\u2019impression de la r\u00e9alit\u00e9, on dira que le <strong>registre litt\u00e9raire<\/strong> est r\u00e9aliste, etc\u2026<\/p>\n<p style=\"text-align: justify\">Il ne faut ainsi pas confondre un <strong>registre litt\u00e9raire<\/strong> avec le genre : un texte peut appartenir au genre th\u00e9\u00e2tral, ou au genre po\u00e9tique, tout en \u00e9tant comique ou tragique. Cependant, il existe des genres plus que d\u2019autres li\u00e9s \u00e0 certains <strong>registres litt\u00e9raires<\/strong>: ainsi, la com\u00e9die th\u00e9\u00e2trale comporte \u00e9videmment bien des exemples de registre comique ; quant \u00e0 l\u2019\u00e9pop\u00e9e (en tant que genre), elle rec\u00e8le de registre \u00e9pique.<\/p>\n<p style=\"text-align: justify\">Prenons garde n\u00e9anmoins, car il y a aussi des passages path\u00e9tiques dans des com\u00e9dies, et quelques situations comiques dans les \u00e9pop\u00e9es\u2026 Dans l&rsquo;ensemble, une \u0153uvre peut comporter plusieurs <strong>registres litt\u00e9raires<\/strong> ; c\u2019est m\u00eame le cas dans 99 % des ouvrages.<\/p>\n<p style=\"text-align: justify\">De m\u00eame, il ne faut pas confondre le <strong>registre litt\u00e9raire<\/strong> d\u2019un texte (tonalit\u00e9) avec le registre de langue d\u2019un texte (soutenu, courant ou familier).<br \/>\nSelon la <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-methode-commentaire-litteraire\/\">m\u00e9thode du commentaire litt\u00e9raire<\/a>, comme dans l\u2019\u00e9tude d\u2019une \u0153uvre, le rep\u00e9rage des <strong>registres litt\u00e9raires<\/strong> est une \u00e9tape indispensable : le dire ne suffira pas, il faudra surtout prouver l\u2019existence de ces registres en examinant les proc\u00e9d\u00e9s litt\u00e9raires (figures de style) associ\u00e9s, la r\u00e9currence de ces registres : c&rsquo;est surtout ce qu\u2019attendent les enseignants et correcteurs\u2026<\/p>\n<p style=\"text-align: justify\">Nous \u00e9tudierons ici <strong>les diff\u00e9rents registres litt\u00e9raires<\/strong> principaux.<\/p>\n<p data-pm-slice=\"1 1 []\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"190573\" class=\"elementor elementor-190573\">\n\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-inner-section elementor-element elementor-element-7f0071b3 elementor-section-content-bottom full_width elementor-section-full_width elementor-section-height-min-height elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"7f0071b3\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-6849d5da ae-bg-gallery-type-default\" data-id=\"6849d5da\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-311d1d62 elementor-widget elementor-widget-heading\" data-id=\"311d1d62\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">TROUVEZ LE MEILLEUR ENSEIGNANT<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14c2df17 elementor-widget elementor-widget-heading\" data-id=\"14c2df17\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">P\u00e9dagogie, bienveillance et suivi<br\/> Profs certifi\u00e9s et agr\u00e9g\u00e9s <\/b><\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-229e3a7 elementor-widget elementor-widget-heading\" data-id=\"229e3a7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Contactez Groupe R\u00e9ussite<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a0746c elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"9a0746c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/cours-particuliers\/francais\/tous-niveaux\/france\/\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\" id=\"CTA_PRD_CP\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Cours particuliers fran\u00e7ais<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-796183a9 elementor-widget elementor-widget-text-editor\" data-id=\"796183a9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: left;\"><b>Avis Google France <\/b><span style=\"color: #e5a430;\"><b>\u2605\u2605\u2605\u2605\u2605<\/b><\/span><b> 4,9 sur 5<\/b><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-26ffe18b ae-bg-gallery-type-default\" data-id=\"26ffe18b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify\">Le registre litt\u00e9raire path\u00e9tique<\/h2>\n<p style=\"text-align: justify\"><strong>D\u00e9finition d&rsquo;un registre litt\u00e9raire<\/strong> path\u00e9tique :<\/p>\n<p style=\"text-align: justify\">Etymologiquement, path\u00e9tique vient du grec \u00ab pathos \u00bb, soit \u00ab piti\u00e9 \u00bb. Un texte dont le <strong>registre litt\u00e9raire<\/strong> est path\u00e9tique vise ainsi \u00e0 susciter de la tristesse, de la compassion, de l\u2019\u00e9motion forte chez le lecteur ; c&rsquo;est le registre des pleurs, des larmes, de la souffrance, de la peine.<\/p>\n<p style=\"text-align: justify\">Proc\u00e9d\u00e9s utilis\u00e9s :<\/p>\n<p style=\"text-align: justify\">&#8211; Champ lexical de la douleur \/ de la souffrance<br \/>\n&#8211; Ponctuation expressive (points d\u2019exclamation pour marquer l\u2019\u00e9motion)<br \/>\n&#8211; Comparaisons et m\u00e9taphores pour caract\u00e9riser la douleur du personnage<br \/>\n&#8211; Amplifications et hyperboles.<\/p>\n<p style=\"text-align: justify\">Exemple de <strong>registre litt\u00e9raire path\u00e9tique<\/strong> :<\/p>\n<p style=\"text-align: justify\">\u00ab L\u2019Agonie \u00bb, po\u00e8me de Ren\u00e9-Fran\u00e7ois Sully Prudhomme (<em>Les solitudes<\/em>, 1869)<br \/>\n<em>Notons ici la r\u00e9currence du champ lexical de la douleur, de la mort<\/em>\u2026<br \/>\n\u00ab Vous qui m&rsquo;aiderez dans mon agonie,<br \/>\nNe me dites rien ;<br \/>\nFaites que j&rsquo;entende un peu d&rsquo;harmonie,<br \/>\nEt je mourrai bien.<br \/>\n(\u2026)<br \/>\nLa musique apaise, enchante et d\u00e9lie<br \/>\nDes choses d&rsquo;en bas :<br \/>\nBercez ma douleur ; je vous en supplie,<br \/>\nNe lui parlez pas. \u00bb<\/p>\n<h2 style=\"text-align: justify\">Le registre litt\u00e9raire lyrique<\/h2>\n<p style=\"text-align: justify\"><strong>D\u00e9finition d&rsquo;un registre litt\u00e9raire<\/strong> lyrique :<\/p>\n<p style=\"text-align: justify\">Le<strong> registre litt\u00e9raire<\/strong> <strong>lyrique<\/strong> vient de la \u00ab lyre \u00bb d\u2019Orph\u00e9e, l\u2019instrument de musique d\u2019Apollon (le nom romain d\u2019Orph\u00e9e). D\u00e8s lors, le registre lyrique est aussi tr\u00e8s li\u00e9 \u00e0 l\u2019expression de la musicalit\u00e9. Plus globalement et surtout, il est le registre litt\u00e9raire de l\u2019expression de l\u2019\u00e9motion personnelle, des sentiments du \u00ab moi \u00bb (sentiments intimes). C&rsquo;est un registre tr\u00e8s li\u00e9 \u00e0 la p\u00e9riode romantique : car les romantiques, dans leurs textes, \u00e9voquaient la nostalgie du temps qui passe, la solitude, la m\u00e9lancolie, le spleen\u2026<\/p>\n<p style=\"text-align: justify\">Proc\u00e9d\u00e9s utilis\u00e9s :<\/p>\n<p style=\"text-align: justify\">&#8211; Champ lexical du sentiment<br \/>\n&#8211; Usage de la premi\u00e8re personne<br \/>\n&#8211; Anaphores<br \/>\n&#8211; Hyperboles et amplifications<br \/>\n&#8211; Assonances et allit\u00e9rations, pour traduire la musicalit\u00e9.<\/p>\n<p style=\"text-align: justify\">Exemple de <strong>registre litt\u00e9raire lyrique<\/strong> :<\/p>\n<p style=\"text-align: justify\">\u00ab El Desdichado \u00bb, <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-poesie\/\">po\u00e9sie<\/a> de G\u00e9rard de Nerval<br \/>\n<em>L\u2019usage de la premi\u00e8re personne, r\u00e9current, fait \u00e9cho \u00e0 l\u2019expression des sentiments intimes avec une forte dose de musicalit\u00e9, de rythme, induit par l\u2019organisation po\u00e9tique des vers notamment par les tirets.<\/em><br \/>\n\u00ab Je suis le T\u00e9n\u00e9breux, \u2013 le Veuf, \u2013 l\u2019Inconsol\u00e9,<br \/>\nLe Prince d\u2019Aquitaine [m\u00e9taphore] \u00e0 la Tour abolie :<br \/>\nMa seule Etoile est morte, \u2013 et mon luth constell\u00e9<br \/>\nPorte le Soleil noir de la M\u00e9lancolie. \u00bb<\/p>\n<p style=\"text-align: justify\">Orph\u00e9e et sa lyre ont donn\u00e9 son nom au registre lyrique (tableau de Fran\u00e7ois Boucher).<\/p>\n<h2 style=\"text-align: justify\">Le registre litt\u00e9raire tragique.<\/h2>\n<p style=\"text-align: justify\"><strong>D\u00e9finition d&rsquo;un registre litt\u00e9raire<\/strong> tragique :<\/p>\n<p style=\"text-align: justify\">Attention ! Il ne faut pas confondre le <strong>registre litt\u00e9raire tragique<\/strong> avec la trag\u00e9die classique (sous-genre <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-theatre\/\">th\u00e9\u00e2tral<\/a>\u00a0que l\u2019on retrouve dans les pi\u00e8ces de Racine ou Corneille par exemple).<\/p>\n<p style=\"text-align: justify\">Cependant, il est vrai que bien des pi\u00e8ces de la trag\u00e9die classique rel\u00e8vent, justement, du registre tragique\u2026 Le registre tragique donne en effet, comme souvent dans les pi\u00e8ces raciniennes, l\u2019illusion du destin ou de la fatalit\u00e9. Les h\u00e9ros apparaissent comme d\u00e9munis, leur sort semblant d\u00e9j\u00e0 d\u00e9cid\u00e9 par une instance sup\u00e9rieure (Dieu, la destin\u00e9e\u2026). C&rsquo;est par la catharsis (le fait de vivre, d\u2019affronter sa crainte) que la terreur que peut inspirer cette fatalit\u00e9, pourra \u00eatre surmont\u00e9e\u2026<\/p>\n<p style=\"text-align: justify\">Mais bien souvent, la m\u00e9lancolie ou le d\u00e9sespoir sont la cons\u00e9quence de cette fatalit\u00e9, les personnes luttant, en vain, face \u00e0 leur destin\u00e9e. La pr\u00e9sence de dieux, rois ou h\u00e9ros est caract\u00e9ristique du registre tragique.<\/p>\n<p style=\"text-align: justify\">Proc\u00e9d\u00e9s utilis\u00e9s :<br \/>\n&#8211; Champ lexical du destin.<br \/>\n&#8211; Registre de langue soutenu.<br \/>\n&#8211; Narration omnisciente.<\/p>\n<p style=\"text-align: justify\">Exemple de <strong>registre litt\u00e9raire tragique<\/strong> :<\/p>\n<p style=\"text-align: justify\">L&rsquo;ensemble des pi\u00e8ces de Racine rel\u00e8vent du registre tragique. Les pi\u00e8ces qui annoncent la r\u00e9alisation d\u2019une proph\u00e9tie, comme <em>\u0152dipe roi<\/em>, le sont aussi. Les <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-roman\/\">romans<\/a> de Zola (Rougon-Macquart) sont eux aussi marqu\u00e9s du sceau de la fatalit\u00e9 (venant de l\u2019h\u00e9r\u00e9dit\u00e9) avec plusieurs passages tragiques.<\/p>\n<p style=\"text-align: justify\">Racine, grand auteur de trag\u00e9dies\u2026 et donc ma\u00eetre du <strong>registre litt\u00e9raire<\/strong> tragique.<\/p>\n<h2 style=\"text-align: justify\">Le registre litt\u00e9raire \u00e9pique<\/h2>\n<p style=\"text-align: justify\"><strong>D\u00e9finition d&rsquo;un registre litt\u00e9raire<\/strong> \u00e9pique :<\/p>\n<p style=\"text-align: justify\">L\u00e0 encore, ce registre litt\u00e9raire est associ\u00e9 (mais ne doit pas \u00eatre confondu) avec un genre : l\u2019\u00e9pop\u00e9e, le genre qui historiquement est associ\u00e9 aux d\u00e9buts de la litt\u00e9rature (<em>\u00c9pop\u00e9e de Gilgamesh, L\u2019Iliade, L\u2019Odyss\u00e9e<\/em>\u2026). Le registre \u00e9pique a pour but de provoquer l\u2019admiration chez le lecteur, \u00e0 travers les hauts faits h\u00e9ro\u00efques qu&rsquo;il retrace (le h\u00e9ros est souvent grandi et doit affronter des adversaires plus forts que lui). Le <strong>registre litt\u00e9raire \u00e9pique<\/strong> se marque aussi par le recours aux forces divines et surnaturelles. D\u00e8s qu&rsquo;il y a pr\u00e9sence de \u00ab super-h\u00e9ros \u00bb, d\u2019aventures en tout genre, de combats contre des forces sup\u00e9rieures, le registre \u00e9pique n&rsquo;est jamais bien loin\u2026<\/p>\n<p style=\"text-align: justify\">Proc\u00e9d\u00e9s utilis\u00e9s :<\/p>\n<p style=\"text-align: justify\">&#8211; Hyperboles et superlatifs pour grandir le h\u00e9ros<br \/>\n&#8211; Champ lexical du courage et du combat<br \/>\n&#8211; Registre de langue soutenu<br \/>\n&#8211; \u00c9pith\u00e8tes dites hom\u00e9riques (<em>L\u2019Aurore aux doigts de roses, Ulysse aux mille ruses<\/em>\u2026)<br \/>\n&#8211; Ponctuation expressive<\/p>\n<p style=\"text-align: justify\">Exemple de <strong>registre litt\u00e9raire \u00e9pique<\/strong> :<\/p>\n<p style=\"text-align: justify\">Virgile, <em>L\u2019Eneide<\/em>, le combat d\u2019\u00c9n\u00e9e contre Turnus (Livre XII)<br \/>\n<em>Cet exemple revient sur le duel entre Virgile (h\u00e9ros \u00e9pique) et son rival \u00ab barbare \u00bb Turnus..<\/em><br \/>\n\u00ab Les deux h\u00e9ros, d\u00e8s que la plaine d\u00e9gag\u00e9e s&rsquo;ouvre \u00e0 eux,<br \/>\nen une attaque rapide, lancent de loin des piques<br \/>\net engagent le combat, au son de leurs boucliers de bronze.<br \/>\nLa terre g\u00e9mit ; \u00e0 ce moment se multiplient et redoublent [hyperboles]\nles coups d&rsquo;\u00e9p\u00e9e : la chance et la valeur se m\u00ealent \u00e0 parts \u00e9gales. \u00bb<br \/>\n(\u2026) \u00ab ainsi \u00c9n\u00e9e le Troyen et le h\u00e9ros daunien courent l&rsquo;un contre l&rsquo;autre<br \/>\navec leurs boucliers, et un fracas \u00e9norme [hyperbole] emplit le ciel.<br \/>\nJupiter [intervention de forces divines] m\u00eame soutient les deux plateaux de la balance. \u00bb<\/p>\n<p>&nbsp;<\/p>\n\t\t<div data-elementor-type=\"section\" data-elementor-id=\"127774\" class=\"elementor elementor-127774\">\n\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-inner-section elementor-element elementor-element-5a7b6a2a elementor-section-content-bottom full_width elementor-section-full_width elementor-section-height-min-height elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"5a7b6a2a\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-66 elementor-inner-column elementor-element elementor-element-749af387 ae-bg-gallery-type-default\" data-id=\"749af387\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b4ed465 elementor-widget elementor-widget-heading\" data-id=\"1b4ed465\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">COURS PARTICULIERS EN LIGNE<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16d47760 elementor-widget elementor-widget-heading\" data-id=\"16d47760\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Nous avons s\u00e9lectionn\u00e9 pour vous les meilleurs professeurs particuliers.<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21a162bf elementor-widget elementor-widget-heading\" data-id=\"21a162bf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">POUR ACC\u00c9L\u00c9RER MA PROGRESSION<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5600477e elementor-align-left elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"5600477e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/cours-en-ligne\/toutes-matieres\/tous-niveaux\/france\/\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\" id=\"CTA_PRD_CP\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Cours particuliers en ligne<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c7a7876 elementor-widget elementor-widget-text-editor\" data-id=\"1c7a7876\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: left;\"><b>Avis Google France <\/b><span style=\"color: #e5a430;\"><b>\u2605\u2605\u2605\u2605\u2605<\/b><\/span><b> 4,9 sur 5<\/b><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-2aa12288 ae-bg-gallery-type-default\" data-id=\"2aa12288\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: justify\">Le registre litt\u00e9raire comique (et ses sous-cat\u00e9gories)<\/h2>\n<p>La suite du <strong>cours sur les registres litt\u00e9raires<\/strong> se trouve sur l&rsquo;application mobile PrepApp. Il est \u00e9galement possible d&rsquo;approfondir <strong>les diff\u00e9rents registres litt\u00e9raires<\/strong> avec un enseignant lors d&rsquo;un cours particuliers de fran\u00e7ais.<\/p>\n<p>De plus, des fiches de lectures sur diff\u00e9rentes \u0153uvres au programme de premi\u00e8re sont disponibles sur notre site :<\/p>\n<ul>\n<li>Les <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-fleurs-du-mal\/\">Fleurs du Mal de Baudelaire<\/a><\/li>\n<li><a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-alcools-apollinaire\/\">Alcools d&rsquo;Apollinaire<\/a><\/li>\n<li>L&rsquo;<a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-exercices-corriges-commentaire-lenterrement-verlaine\/\">enterrement de Verlaine<\/a><\/li>\n<li>Les <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-lettres-persanes\/\">Lettres Persanes de Montesquieu<\/a><\/li>\n<li>Les <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-memoires-hadrien-yourcenar\/\">M\u00e9moires d&rsquo;Hadrien de Yourcenar<\/a><\/li>\n<li>Les <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-contemplations-hugo\/\">Contemplations de Hugo<\/a><\/li>\n<li>Les <a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-fables-la-fontaine\/\">Fables de la Fontaine<\/a><\/li>\n<li><a href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-le-malade-imaginaire-moliere\/\">Le Malade Imaginaire de Moli\u00e8re<\/a><\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Les registres litt\u00e9raires R\u00e9sum\u00e9 de cours Exercices et corrig\u00e9s Cours en ligne de Fran\u00e7ais en Premi\u00e8re Le cours en ligne de fran\u00e7ais en premi\u00e8re sur les registres litt\u00e9raires est indispensable \u00e0 conna\u00eetre car les registres litt\u00e9raires permettent de comprendre et d&rsquo;analyser une \u0153uvre litt\u00e9raire. Ce cours est donc essentiel \u00e0 conna\u00eetre afin de pr\u00e9parer le [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.2.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Les registres litt\u00e9raires : cours en ligne gratuit<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez notre cours en ligne gratuit sur les registres litt\u00e9raires : registre path\u00e9tique, registre lyrique, tragique, \u00e9pique, comique...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-registres-litteraires\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les registres litt\u00e9raires : cours en ligne gratuit\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez notre cours en ligne gratuit sur les registres litt\u00e9raires : registre path\u00e9tique, registre lyrique, tragique, \u00e9pique, comique...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-registres-litteraires\/\" \/>\n<meta property=\"og:site_name\" content=\"Groupe R\u00e9ussite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GroupeReussiteOfficiel\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-12T12:35:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2026\/05\/logo-groupe-reussite-carre.png\" \/>\n\t<meta property=\"og:image:width\" content=\"170\" \/>\n\t<meta property=\"og:image:height\" content=\"180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@GroupeReussite\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-registres-litteraires\/\",\"url\":\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-registres-litteraires\/\",\"name\":\"Les registres litt\u00e9raires : cours en ligne gratuit\",\"isPartOf\":{\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/#website\"},\"datePublished\":\"2020-11-13T10:10:49+00:00\",\"dateModified\":\"2023-10-12T12:35:44+00:00\",\"description\":\"D\u00e9couvrez notre cours en ligne gratuit sur les registres litt\u00e9raires : registre path\u00e9tique, registre lyrique, tragique, \u00e9pique, comique...\",\"breadcrumb\":{\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-registres-litteraires\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-registres-litteraires\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-registres-litteraires\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/groupe-reussite.fr\/ressources\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cours sur les registres litt\u00e9raires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/#website\",\"url\":\"https:\/\/groupe-reussite.fr\/ressources\/\",\"name\":\"Groupe R\u00e9ussite - Cours particuliers et stages de vacances\",\"description\":\"Stage et Cours particuliers maths, fran\u00e7ais, anglais, informatique, physique chimie\",\"publisher\":{\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/groupe-reussite.fr\/ressources\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/#organization\",\"name\":\"Groupe R\u00e9ussite - Cours particuliers et stages de vacances\",\"url\":\"https:\/\/groupe-reussite.fr\/ressources\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2026\/05\/logo-groupe-reussite-carre.png\",\"contentUrl\":\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2026\/05\/logo-groupe-reussite-carre.png\",\"width\":170,\"height\":180,\"caption\":\"Groupe R\u00e9ussite - Cours particuliers et stages de vacances\"},\"image\":{\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/GroupeReussiteOfficiel\/\",\"https:\/\/twitter.com\/GroupeReussite\",\"https:\/\/www.youtube.com\/c\/GroupeReussite\",\"https:\/\/www.instagram.com\/groupe_reussite_officiel\/\",\"https:\/\/fr.linkedin.com\/company\/groupe-reussite\",\"https:\/\/www.tiktok.com\/@groupereussite\",\"https:\/\/fr.pinterest.com\/GroupeReussite\/\",\"https:\/\/www.reddit.com\/user\/Groupe-Reussite\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les registres litt\u00e9raires : cours en ligne gratuit","description":"D\u00e9couvrez notre cours en ligne gratuit sur les registres litt\u00e9raires : registre path\u00e9tique, registre lyrique, tragique, \u00e9pique, comique...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-registres-litteraires\/","og_locale":"fr_FR","og_type":"article","og_title":"Les registres litt\u00e9raires : cours en ligne gratuit","og_description":"D\u00e9couvrez notre cours en ligne gratuit sur les registres litt\u00e9raires : registre path\u00e9tique, registre lyrique, tragique, \u00e9pique, comique...","og_url":"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-registres-litteraires\/","og_site_name":"Groupe R\u00e9ussite","article_publisher":"https:\/\/www.facebook.com\/GroupeReussiteOfficiel\/","article_modified_time":"2023-10-12T12:35:44+00:00","og_image":[{"width":170,"height":180,"url":"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2026\/05\/logo-groupe-reussite-carre.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@GroupeReussite","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-registres-litteraires\/","url":"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-registres-litteraires\/","name":"Les registres litt\u00e9raires : cours en ligne gratuit","isPartOf":{"@id":"https:\/\/groupe-reussite.fr\/ressources\/#website"},"datePublished":"2020-11-13T10:10:49+00:00","dateModified":"2023-10-12T12:35:44+00:00","description":"D\u00e9couvrez notre cours en ligne gratuit sur les registres litt\u00e9raires : registre path\u00e9tique, registre lyrique, tragique, \u00e9pique, comique...","breadcrumb":{"@id":"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-registres-litteraires\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-registres-litteraires\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/groupe-reussite.fr\/ressources\/cours-en-ligne-premiere-registres-litteraires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/groupe-reussite.fr\/ressources\/"},{"@type":"ListItem","position":2,"name":"Cours sur les registres litt\u00e9raires"}]},{"@type":"WebSite","@id":"https:\/\/groupe-reussite.fr\/ressources\/#website","url":"https:\/\/groupe-reussite.fr\/ressources\/","name":"Groupe R\u00e9ussite - Cours particuliers et stages de vacances","description":"Stage et Cours particuliers maths, fran\u00e7ais, anglais, informatique, physique chimie","publisher":{"@id":"https:\/\/groupe-reussite.fr\/ressources\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/groupe-reussite.fr\/ressources\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/groupe-reussite.fr\/ressources\/#organization","name":"Groupe R\u00e9ussite - Cours particuliers et stages de vacances","url":"https:\/\/groupe-reussite.fr\/ressources\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/groupe-reussite.fr\/ressources\/#\/schema\/logo\/image\/","url":"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2026\/05\/logo-groupe-reussite-carre.png","contentUrl":"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2026\/05\/logo-groupe-reussite-carre.png","width":170,"height":180,"caption":"Groupe R\u00e9ussite - Cours particuliers et stages de vacances"},"image":{"@id":"https:\/\/groupe-reussite.fr\/ressources\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GroupeReussiteOfficiel\/","https:\/\/twitter.com\/GroupeReussite","https:\/\/www.youtube.com\/c\/GroupeReussite","https:\/\/www.instagram.com\/groupe_reussite_officiel\/","https:\/\/fr.linkedin.com\/company\/groupe-reussite","https:\/\/www.tiktok.com\/@groupereussite","https:\/\/fr.pinterest.com\/GroupeReussite\/","https:\/\/www.reddit.com\/user\/Groupe-Reussite\/"]}]}},"_links":{"self":[{"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/pages\/75668"}],"collection":[{"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/comments?post=75668"}],"version-history":[{"count":2,"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/pages\/75668\/revisions"}],"predecessor-version":[{"id":191744,"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/pages\/75668\/revisions\/191744"}],"wp:attachment":[{"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/media?parent=75668"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}