{"id":68811,"date":"2020-09-22T11:33:31","date_gmt":"2020-09-22T10:33:31","guid":{"rendered":"https:\/\/groupe-reussite.fr\/?p=68811"},"modified":"2026-06-17T16:23:01","modified_gmt":"2026-06-17T15:23:01","slug":"resultats-eleves-prepa-hec","status":"publish","type":"post","link":"https:\/\/groupe-reussite.fr\/ressources\/blog\/resultats-eleves-prepa-hec\/","title":{"rendered":"R\u00e9sultats et avis des \u00e9l\u00e8ves Groupe R\u00e9ussite en pr\u00e9pa ECG"},"content":{"rendered":"<h2 style=\"text-align: justify;\">80 % des \u00e9l\u00e8ves Groupe R\u00e9ussite dans le Top 6 des \u00e9coles de commerce :<\/h2>\n<p style=\"text-align: justify;\">80% des \u00e9l\u00e8ves en pr\u00e9pa ECG qui ont d\u00e9cid\u00e9 de se faire accompagner par Groupe R\u00e9ussite, que ce soit en <strong>cours particuliers<\/strong> ou durant nos stages intensifs de vacances d\u00e9crochent l&rsquo;admissibilit\u00e9 et entrent dans le <strong>top 6 des \u00e9coles de commerce fran\u00e7aises<\/strong> (<a href=\"https:\/\/groupe-reussite.fr\/ressources\/blog\/comparatif-hec-essec-escp\/\">HEC, ESSEC, ESCP<\/a>, EDHEC, EM Lyon et GEM), dont beaucoup r\u00e9ussissent m\u00eame les \u00e9preuves d&rsquo;admissibilit\u00e9 du top 3.<\/p>\n<p style=\"text-align: justify;\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"41596\" class=\"elementor elementor-41596\">\n\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-inner-section elementor-element elementor-element-7c626203 elementor-section-content-bottom full_width elementor-section-full_width elementor-section-height-min-height elementor-hidden-mobile elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"7c626203\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5f116209 ae-bg-gallery-type-default\" data-id=\"5f116209\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-34fcbc63 ae-bg-gallery-type-default\" data-id=\"34fcbc63\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a7543e1 elementor-widget elementor-widget-heading\" data-id=\"1a7543e1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">STAGE INTENSIF POUR ECG 1<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43e6578f elementor-widget elementor-widget-heading\" data-id=\"43e6578f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Profite de tes vacances pour gagner des points en maths<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2b0c785f elementor-widget elementor-widget-text-editor\" data-id=\"2b0c785f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong><span style=\"color: #e5a431\">96%<\/span><\/strong> \u00a0<span style=\"color: #183153\">de r\u00e9ussite aux concours<\/span><br \/><span style=\"color: #97caef\"><strong>84%<\/strong><\/span> <span style=\"color: #183153\">dans le TOP 10<\/span><br \/><strong><span style=\"color: #a64d79\">99%<\/span><\/strong> <span style=\"color: #183153\">de recommandation \u00e0 leurs amis<\/span><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a9dfb97 elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"5a9dfb97\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/stages\/toutes-matieres\/ecg1\/france\/toutes-periodes\/\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\" id=\"CTA_PRD_STAGE\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Stage intensif pr\u00e9pa ECG 1<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44c41e45 elementor-widget elementor-widget-text-editor\" data-id=\"44c41e45\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center\"><b>Avis Google France <\/b><span style=\"color: #e5a430\"><b>\u2605\u2605\u2605\u2605\u2605<\/b><\/span><b> 4,9 sur 5<\/b><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n<h3 style=\"text-align: justify;\">95 % des \u00e9l\u00e8ves Groupe R\u00e9ussite dans le top 10 des \u00e9coles de commerce :<\/h3>\n<p style=\"text-align: justify;\">La quasi-totalit\u00e9 de nos \u00e9l\u00e8ves qui prennent des cours particuliers r\u00e9guliers et ont suivi une ou plusieurs semaines intensives de r\u00e9visions r\u00e9ussissent chaque ann\u00e9e \u00e0 entrer dans le <strong>top 10 du classement des meilleures \u00e9coles de commerce fran\u00e7aises. <\/strong>On ajoute \u00e0 la liste pr\u00e9c\u00e9dente les \u00e9coles suivantes : NEOMA, Audencia, SKEMA, TBS, Kedge. Nous avons pris pour ces r\u00e9sultats uniquement les \u00e9l\u00e8ves qui ont suivi au moins une dizaine d&rsquo;heures en cours particuliers et qui ont particip\u00e9 \u00e0 au moins un <a href=\"https:\/\/groupe-reussite.fr\/stages\/toutes-matieres\/prepa-hec\/france\/toutes-periodes\/\">stage intensif en pr\u00e9pa ECG<\/a>.<\/p>\n<p>En session de vacances, nous proposons un accompagnement avec des <strong>professeurs agr\u00e9g\u00e9s<\/strong>, soit en poste CPGE, soit kholleurs. En <a href=\"https:\/\/groupe-reussite.fr\/cours-particuliers\/toutes-matieres\/prepa-hec\/france\/\">cours particuliers en pr\u00e9pa ECG<\/a>, nous avons des professeurs agr\u00e9g\u00e9s, mais \u00e9galement des \u00e9tudiants qui ont une dimension coaching plus importante, surtout pour des \u00e9l\u00e8ves en difficult\u00e9 qui ont besoin d&rsquo;accompagnement en confiance en soi \u00e9galement. <strong>M\u00e9thodologie, bienveillance et coaching<\/strong> permettent aux \u00e9l\u00e8ves de r\u00e9ellement progresser et de se surprendre sur leurs capacit\u00e9s.<\/p>\n<p style=\"text-align: justify;\">Voici quelques r\u00e9sultats d&rsquo;\u00e9l\u00e8ves de Groupe R\u00e9ussite en pr\u00e9pa HEC aux concours BCE et Ecricome \u00e9crits et oraux.<\/p>\n<p style=\"text-align: justify;\"><strong>R\u00e9sultats de David, entr\u00e9 \u00e0 HEC ayant fait sa pr\u00e9pa \u00e0 Stanislas \u00e0 Paris<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" class=\" wp-image-68959 aligncenter\" src=\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2020\/09\/resultats-david-prepa-hec.jpg\" alt=\"R\u00e9sultats de David en prepa HEC\" width=\"524\" height=\"609\" \/><\/p>\n<p style=\"text-align: justify;\">David est un \u00e9tudiant qui a effectu\u00e9 un travail extr\u00eamement rigoureux pour obtenir ces <strong>r\u00e9sultats au concours de la BCE<\/strong>. On note que c&rsquo;est un \u00e9tudiant qui a r\u00e9ussi \u00e0 garder une bonne homog\u00e9n\u00e9it\u00e9 de niveau parmi toutes les mati\u00e8res. M\u00eame si d&rsquo;excellentes notes ont \u00e9t\u00e9 obtenues en math\u00e9matiques pour <strong>HEC Paris<\/strong>, l&rsquo;<strong>ESSEC<\/strong> ou encore un double 20 aux \u00e9preuves EML et Edhec. David n&rsquo;a pas d\u00e9m\u00e9rit\u00e9 non plus dans les mati\u00e8res litt\u00e9raires, comme le montre son tr\u00e8s bon 17 sur l&rsquo;\u00e9preuve de contraction de texte.<\/p>\n<p style=\"text-align: justify;\"><strong>R\u00e9sultats de Capucine, entr\u00e9e \u00e0 HEC et ancienne \u00e9tudiante de Franklin<\/strong><\/p>\n<p style=\"text-align: justify;\"><img loading=\"lazy\" class=\" wp-image-68863 aligncenter\" src=\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2020\/09\/resultats-prepa-hec-marine.png\" alt=\"R\u00e9sultats d'\u00e9tudiantes au concours de la BCE\" width=\"611\" height=\"518\" \/> Capucine, comme David, a r\u00e9ussi \u00e0 obtenir des r\u00e9sultats relativement homog\u00e8nes. M\u00eame si, tout comme David, les notes en math\u00e9matiques sont remarquables. Capucine a \u00e9galement de tr\u00e8s bonnes notes en langues (anglais, allemand), ainsi qu&rsquo;\u00e0 l&rsquo;\u00e9preuve de culture g\u00e9n\u00e9rale. Les notes aux oraux de HEC, les notes aux oraux de l&rsquo;ESSEC, et \u00e0 l&rsquo;ESCP, sont, quant \u00e0 elles, un peu plus h\u00e9t\u00e9rog\u00e8nes, mais restent de tr\u00e8s bonnes notes vu la difficult\u00e9 des \u00e9preuves et le syst\u00e8me de notation tr\u00e8s exigeant.<\/p>\n<p><strong>R\u00e9sultats de Jean, entr\u00e9 \u00e0 l&rsquo;EDHEC et ancien de Notre-Dame du Grandchamp \u00e0 Versailles.<\/strong><\/p>\n<p><img loading=\"lazy\" class=\"wp-image-68870 aligncenter\" src=\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2020\/09\/resultats-nicolas-prepa-hec-notre-dame-de-grandchamps-edhec.jpg\" alt=\"R\u00e9sultats de Nicolas \u00e0 l'EDHEC\" width=\"375\" height=\"526\" \/><\/p>\n<p style=\"text-align: justify;\">Jean, \u00e9tudiant en prepa HEC au lyc\u00e9e priv\u00e9 Notre-Dame de Grandchamp \u00e0 Versailles, a r\u00e9ussi \u00e0 int\u00e9grer l&rsquo;EDHEC \u00e0 la fin de sa CPGE. Malgr\u00e9 quelques petites notes en dessous de la moyenne, Jean a su compenser ses faiblesses par des bonnes notes dans les \u00e9preuves de math\u00e9matiques et de langues vivantes, ainsi qu&rsquo;un 12 en contraction de texte, qui est une note plut\u00f4t correcte face \u00e0 la difficult\u00e9 de l&rsquo;\u00e9preuve.<\/p>\n<p><strong>Exemple de mail d&rsquo;admission \u00e0 HEC Paris, re\u00e7u par l&rsquo;un de nos \u00e9l\u00e8ves en pr\u00e9pa HEC \u00e0 Henri IV :\u00a0<\/strong><\/p>\n<p><img loading=\"lazy\" class=\" wp-image-68962 aligncenter\" src=\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2020\/09\/admission-hec-paris.jpg\" alt=\"Admission \u00e0 HEC Paris\" width=\"782\" height=\"442\" \/><\/p>\n\t\t<div data-elementor-type=\"section\" data-elementor-id=\"41578\" class=\"elementor elementor-41578\">\n\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-inner-section elementor-element elementor-element-566798e8 elementor-section-content-bottom full_width elementor-section-full_width elementor-section-height-min-height elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"566798e8\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-217421f7 ae-bg-gallery-type-default\" data-id=\"217421f7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-20c26d82 ae-bg-gallery-type-default\" data-id=\"20c26d82\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6771f4a5 elementor-widget elementor-widget-heading\" data-id=\"6771f4a5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">STAGE INTENSIF EN ECG 2<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-773e84eb elementor-widget elementor-widget-heading\" data-id=\"773e84eb\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Profite de tes vacances pour gagner des points aux concours.<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4ca01263 elementor-widget elementor-widget-text-editor\" data-id=\"4ca01263\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong><span style=\"color: #e5a431;\">96%<\/span><\/strong> \u00a0<span style=\"color: #183153;\">de r\u00e9ussite aux concours<\/span><br \/><span style=\"color: #97caef;\"><strong>74%<\/strong><\/span> <span style=\"color: #183153;\">dans le TOP 5<\/span><br \/><strong><span style=\"color: #a64d79;\">99%<\/span><\/strong> <span style=\"color: #183153;\">de recommandation \u00e0 leurs amis<\/span><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e5efdfe elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"1e5efdfe\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/stages\/toutes-matieres\/ecg2\/france\/toutes-periodes\/\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\" id=\"CTA_PRD_STAGE\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">stage en pr\u00e9pa ECG 2<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52467864 elementor-widget elementor-widget-text-editor\" data-id=\"52467864\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><b>Avis Google France <\/b><span style=\"color: #e5a430;\"><b>\u2605\u2605\u2605\u2605\u2605<\/b><\/span><b> 4,9 sur 5<\/b><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n<h2>Les lyc\u00e9es de provenance des \u00e9l\u00e8ves Groupe R\u00e9ussite en pr\u00e9pa HEC<\/h2>\n<p style=\"text-align: justify;\">Les \u00e9tudiants de pr\u00e9pa \u00e9conomique qui participent aux stages de r\u00e9visions viennent de <strong>toute la France<\/strong>. En effet, tous nos stages se d\u00e9roulent \u00e0 Paris, mais tous les \u00e9l\u00e8ves de France et m\u00eame de l&rsquo;\u00e9tranger peuvent y participer, notamment en visio. Groupe R\u00e9ussite accueille chaque ann\u00e9e des \u00e9tudiants venant de <strong>prepa parisiennes<\/strong> ou en Ile-de-France, comme St Louis de Gonzague, Henri IV, Janson-de-Sailly, Montaigne, Stanislas, Louis-le-Grand, Sainte-Genevi\u00e8ve, Hoche ou encore Notre-Dame-de-Sainte-Croix . Mais de nombreux \u00e9tudiants de province viennent \u00e9galement participer \u00e0 ces semaines. Parmi ces \u00e9tudiants, on retrouve les lyc\u00e9es Le Parc, Sainte-Marie, Amp\u00e8re et les Chartreux (<a href=\"https:\/\/groupe-reussite.fr\/cours-particuliers\/toutes-matieres\/tous-niveaux\/lyon\/\">cours \u00e0 Lyon<\/a>), Saint-Paul (Lille), Vial (Nantes), Chateaubriand (Rennes), Kl\u00e9ber (<a href=\"https:\/\/groupe-reussite.fr\/cours-particuliers\/toutes-matieres\/tous-niveaux\/strasbourg\/\">cours \u00e0 Strasbourg<\/a>) ou encore le lyc\u00e9e Joffre \u00e0 Montpellier.<\/p>\n<h2 style=\"text-align: justify;\">Les avis et t\u00e9moignages des \u00e9l\u00e8ves de pr\u00e9pa ECG sur Groupe R\u00e9ussite<\/h2>\n<p style=\"text-align: justify;\">Beaucoup de parents d&rsquo;\u00e9l\u00e8ves ou d&rsquo;\u00e9tudiants contactent Groupe R\u00e9ussite suite \u00e0 une recommandation d&rsquo;un ami, d&rsquo;une connaissance, d&rsquo;un professeur, d&rsquo;un fr\u00e8re ou d&rsquo;une s\u0153ur. Plus qu&rsquo;une simple mise en relation entre l&rsquo;\u00e9tudiant et un professeur particulier, Groupe R\u00e9ussite assure un suivi de tous les \u00e9tudiants.<\/p>\n<p style=\"text-align: justify;\">Le but \u00e9tant d&rsquo;\u00eatre s\u00fbr que le professeur correspond parfaitement aux demandes et aux attentes des \u00e9l\u00e8ves, que ce soit dans le domaine scolaire, mais aussi sur le c\u00f4t\u00e9 humain. C&rsquo;est d&rsquo;ailleurs pour cela, qu&rsquo;il est possible pour tous les \u00e9tudiants qui prennent des cours particuliers \u00e0 Paris et dans toute la France, de demander \u00e0 changer de professeur, si celui qui leur donne cours actuellement ne leur convient pas ou ne leur convient plus.<\/p>\n<p style=\"text-align: justify;\">En ce qui concerne les stages de vacances, ils sont dispens\u00e9s uniquement par les <strong>meilleurs professeurs de Groupe R\u00e9ussite<\/strong>. Comme pour les cours \u00e0 domicile ou en visio, le principal objectif est de faire progresser significativement tous les \u00e9l\u00e8ves, mais le c\u00f4t\u00e9 humain est \u00e9galement pr\u00e9dominant.<\/p>\n<p style=\"text-align: justify;\">En effet, tous les professeurs qui donnent cours pendant les sessions, se tiennent \u00e0 l&rsquo;enti\u00e8re disposition des \u00e9l\u00e8ves pour r\u00e9pondre \u00e0 leurs interrogations, pour les conseiller, mais aussi pour les rassurer quant \u00e0 d&rsquo;\u00e9ventuelles inqui\u00e9tudes. \u00c0 tous les stages, nous remarquons que de nombreux \u00e9l\u00e8ves sollicitent leurs professeurs, le matin avant que le cours commence, pendant les pauses et m\u00eame apr\u00e8s les cours en fin de journ\u00e9e. Les professeurs sont, quant \u00e0 eux, ravis de pouvoir accompagner et mener les \u00e9l\u00e8ves vers la r\u00e9ussite et l&rsquo;excellence.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" class=\"wp-image-68875 aligncenter\" src=\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2020\/09\/avis-alycia.jpg\" alt=\"Avis d'Alycia sur Groupe R\u00e9ussite\" width=\"682\" height=\"255\" \/><\/p>\n<p><img loading=\"lazy\" class=\" wp-image-68876 aligncenter\" src=\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2020\/09\/avis-annabelle.jpg\" alt=\"Avis d'Annabelle sur Groupe R\u00e9ussite\" width=\"686\" height=\"292\" \/><\/p>\n<p><img loading=\"lazy\" class=\" wp-image-68877 aligncenter\" src=\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2020\/09\/avis-camille.jpg\" alt=\"Avis de Camille sur Groupe R\u00e9ussite\" width=\"685\" height=\"239\" \/><\/p>\n<p><img loading=\"lazy\" class=\" wp-image-68878 aligncenter\" src=\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2020\/09\/avis-frederique.jpg\" alt=\"Avis de Fr\u00e9d\u00e9rique sur Groupe R\u00e9ussite\" width=\"690\" height=\"317\" \/><\/p>\n<p><img loading=\"lazy\" class=\" wp-image-68879 aligncenter\" src=\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2020\/09\/avis-genevieve.jpg\" alt=\"Avis de Genevi\u00e8ve sur Groupe R\u00e9ussite\" width=\"684\" height=\"248\" \/><\/p>\n<p><img loading=\"lazy\" class=\" wp-image-68880 aligncenter\" src=\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2020\/09\/avis-hassan.jpg\" alt=\"Avis de Hassan sur Groupe R\u00e9ussite\" width=\"686\" height=\"208\" \/><\/p>\n<p><img loading=\"lazy\" class=\" wp-image-68881 aligncenter\" src=\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2020\/09\/avis-remi.jpg\" alt=\"Avis de R\u00e9mi sur Groupe R\u00e9ussite\" width=\"682\" height=\"232\" \/><\/p>\n<h2 style=\"text-align: justify;\">R\u00e9ussir sa CPGE avec Groupe R\u00e9ussite<\/h2>\n<p style=\"text-align: justify;\">Depuis de nombreuses ann\u00e9es, Groupe R\u00e9ussite accompagne, suit et coache des centaines d&rsquo;\u00e9l\u00e8ves par an en pr\u00e9pa dans le but de leur donner les moyens d&rsquo;atteindre leurs objectifs et d&rsquo;int\u00e9grer une des meilleures \u00e9coles de commerce en France ou m\u00eame \u00e0 l&rsquo;\u00e9tranger.<\/p>\n<p style=\"text-align: justify;\">Les \u00e9tudiants qui souhaitent \u00eatre admis dans les <strong>meilleures \u00e9coles de commerce du classement<\/strong> doivent se pr\u00e9parer d\u00e8s la premi\u00e8re ann\u00e9e aux concours. Pour mettre toutes les chances de leur c\u00f4t\u00e9 et pouvoir faire la diff\u00e9rence.<\/p>\n<p style=\"text-align: justify;\">Les cours particuliers ou les stages intensifs s&rsquo;adaptent \u00e0 tous les \u00e9l\u00e8ves et \u00e0 tous les objectifs. Bien \u00e9videmment, tous les \u00e9l\u00e8ves souhaitent se pr\u00e9parer aux concours post pr\u00e9pa, mais certains souhaitent \u00e9galement s&rsquo;exercer de fa\u00e7on tr\u00e8s approfondie dans le but de <a href=\"https:\/\/groupe-reussite.fr\/ressources\/blog\/majorer-prepa\/\">majorer en prepa<\/a>, et d&rsquo;autres souhaitent simplement acc\u00e9der \u00e0 une \u00e9cole au <strong>top 10 du classement des \u00e9coles de commerce<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Groupe R\u00e9ussite, met un point d&rsquo;honneur \u00e0 r\u00e9pondre \u00e0 <strong>tous les souhaits de ses \u00e9tudiants<\/strong>. Toutes les sessions, comme le <a href=\"https:\/\/groupe-reussite.fr\/stages\/toutes-matieres\/prepa-hec\/france\/pre-rentree\/\">stage de pr\u00e9-rentr\u00e9e en pr\u00e9pa ECG<\/a> tout comme celui de Toussaint ou de f\u00e9vrier, proposent 2 classes de niveau, une classe normale et une classe de niveau avanc\u00e9. Ainsi, tous les \u00e9l\u00e8ves, quel que soit leur niveau au moment du stage et leurs objectifs, tous trouveront l&rsquo;accompagnement le plus ad\u00e9quat \u00e0 ce qu&rsquo;ils recherchent.<\/p>\n<p style=\"text-align: justify;\">Les cours fonctionnent de la m\u00eame mani\u00e8re. Un <strong>professeur particulier<\/strong> est recommand\u00e9 \u00e0 un \u00e9tudiant si et seulement s&rsquo;il correspond au profil de l&rsquo;\u00e9tudiant. L&rsquo;\u00e9tudiant lui-m\u00eame peut d&rsquo;ailleurs \u00e9galement demander un profil sp\u00e9cifique (professeur en poste au lyc\u00e9e, prepa, universit\u00e9, \u00e9tudiants de grandes \u00e9coles, doctorant, ancien professeur&#8230;) pour ses cours particuliers \u00e0 domicile. Chez Groupe R\u00e9ussite, tous les professeurs qui donnent des cours particuliers ont \u00e9t\u00e9 s\u00e9lectionn\u00e9s pour leur haut niveau de qualification, mais \u00e9galement pour la qualit\u00e9 de leur accompagnement m\u00ealant bienveillance, altruisme, partage et \u00e9coute.<\/p>\n<p style=\"text-align: justify;\">Un accompagnement compl\u00e9mentaire aux cours donn\u00e9s par les professeurs de prepa, est fortement recommand\u00e9, voire indispensable pour r\u00e9ussir les concours post-prepa et int\u00e9grer des \u00e9coles de commerce comme HEC Paris, l&rsquo;ESSEC, l&rsquo;EDHEC, NEOMA, l&rsquo;ESCP ou encore KEDGE.<\/p>\n<p style=\"text-align: justify;\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"184476\" class=\"elementor elementor-184476\">\n\t\t\t\t\t<div class=\"elementor-section-wrap\">\n\t\t\t\t\t\t\t\t<section class=\"has_ae_slider elementor-section elementor-inner-section elementor-element elementor-element-3abc81db elementor-section-content-bottom full_width elementor-section-full_width elementor-section-height-min-height elementor-section-height-default ae-bg-gallery-type-default\" data-id=\"3abc81db\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-narrow\">\n\t\t\t\t\t\t\t<div class=\"elementor-row\">\n\t\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-36477ac0 ae-bg-gallery-type-default\" data-id=\"36477ac0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"has_ae_slider elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-725fe2df ae-bg-gallery-type-default\" data-id=\"725fe2df\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-column-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3953cdda elementor-widget elementor-widget-heading\" data-id=\"3953cdda\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">STAGE VACANCES PR\u00c9PA HEC<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43028294 elementor-widget elementor-widget-heading\" data-id=\"43028294\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Vise les meilleures \u00e9coles de commerce de France<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bf341dd elementor-widget elementor-widget-text-editor\" data-id=\"7bf341dd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p><strong><span style=\"color: #e5a431;\">&#8211;&gt;<\/span><\/strong> Les meilleurs professeurs de CPGE<br \/><span style=\"color: #97caef;\"><strong>&#8211;&gt;<\/strong><\/span> Tous les exercices et annales incontournables<br \/><strong><span style=\"color: #a64d79;\">&#8211;&gt; <\/span><\/strong><span style=\"color: #183153;\">80% des \u00e9l\u00e8ves dans le top 5<\/span><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1035fb3e elementor-align-center elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"1035fb3e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/groupe-reussite.fr\/stages\/toutes-matieres\/prepa-hec\/france\/toutes-periodes\/\" target=\"_blank\" class=\"elementor-button-link elementor-button elementor-size-md\" role=\"button\" id=\"CTA_PRD_STAGE\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Stage de maths en prepa HEC<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e67a8f0 elementor-widget elementor-widget-text-editor\" data-id=\"2e67a8f0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-text-editor elementor-clearfix\">\n\t\t\t\t<p style=\"text-align: center;\"><b>Avis Google France <\/b><span style=\"color: #e5a430;\"><b>\u2605\u2605\u2605\u2605\u2605<\/b><\/span><b> 4,9 sur 5<\/b><\/p>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\n<h2><\/h2>\n<h2 style=\"text-align: justify;\">Qu&rsquo;est-ce que les prepa ECG ?<\/h2>\n<p style=\"text-align: justify;\">Bien que les CPGE ne soient pas les v\u0153ux les plus demand\u00e9s sur Parcoursup, ils arrivent tout de m\u00eame en 4e position apr\u00e8s les licences, les BTS et les DUT. Sur les 85 070 \u00e9tudiants de CPGE, 19 279 \u00e9tudiants ont choisi d&rsquo;int\u00e9grer une prepa \u00e9conomique et commerciale. En 10 ans, on observe une augmentation de pr\u00e8s de 800 \u00e9l\u00e8ves.<\/p>\n<p style=\"text-align: justify;\">La prepa ECG que ce soit en maths approfondies ou en maths appliqu\u00e9es, est fortement pris\u00e9e par les \u00e9tudiants d\u00e9j\u00e0 int\u00e9ress\u00e9s par le domaine du commerce, mais pas que. De nombreux \u00e9l\u00e8ves choisissent d&rsquo;int\u00e9grer cette voie, car elle permet tout simplement d&rsquo;acc\u00e9der \u00e0 de tr\u00e8s nombreux d\u00e9bouch\u00e9s.<\/p>\n<p style=\"text-align: justify;\">Les prepa bien qu&rsquo;elles soient connues et reconnues, comme des cursus demandant un travail exigeant aux \u00e9tudiants, restent une voie privil\u00e9gi\u00e9e pour des milliers d&rsquo;\u00e9tudiants chaque ann\u00e9e. En effet, les prepa HEC permettent d&rsquo;int\u00e9grer des <strong>\u00e9coles de commerce de haut niveau<\/strong>, reconnues dans le monde entier. De plus, un cursus en CPGE est un crit\u00e8re appr\u00e9ci\u00e9 des recruteurs.<\/p>\n<p style=\"text-align: justify;\">Bien que les 2 ann\u00e9es de CPGE soient dures et exigeantes, il en est de m\u00eame pour les concours post prepa, que ce soit pour les \u00e9preuves du concours Ecricome ou les \u00e9preuves du concours de la BCE.<\/p>\n<p>Lire d&rsquo;autres articles pour r\u00e9ussir en pr\u00e9pa ECG :<\/p>\n<ul>\n<li><a href=\"https:\/\/groupe-reussite.fr\/ressources\/blog\/comment-reussir-prepa-hec-scientifique\/\">Comment r\u00e9ussir en pr\u00e9pa ECG ?<\/a><\/li>\n<li><a href=\"https:\/\/groupe-reussite.fr\/ressources\/blog\/prepa-privee-hec-comparaison\/\">Comparaison des pr\u00e9pa ECG priv\u00e9es Ipesup Int\u00e9grale<\/a><\/li>\n<li><a href=\"https:\/\/groupe-reussite.fr\/ressources\/blog\/calendrier-concours-prepa-hec\/\">Dates des concours BCE et Ecricome<\/a><\/li>\n<li><a href=\"https:\/\/groupe-reussite.fr\/ressources\/blog\/progresser-maths-prepa-hec\/\">Comment progresser en maths en pr\u00e9pa ECG ?<\/a><\/li>\n<li><a href=\"https:\/\/groupe-reussite.fr\/ressources\/blog\/pourquoi-cuber-en-prepa-hec\/\">Pourquoi cuber en pr\u00e9pa ECG ?<\/a><\/li>\n<li><a href=\"https:\/\/groupe-reussite.fr\/ressources\/blog\/prepa-rentree-hec\/\">R\u00e9ussir la rentr\u00e9e en prepa ECG<\/a><\/li>\n<li><a href=\"https:\/\/groupe-reussite.fr\/ressources\/blog\/repartir-efforts-maths-autres-matieres-en-prepa-hec\/\">S&rsquo;organiser en pr\u00e9pa ECG entre les maths et les autres mati\u00e8res<\/a><\/li>\n<li><a href=\"https:\/\/groupe-reussite.fr\/ressources\/blog\/comparatif-hec-essec-escp\/\">Comparatif HEC, ESSEC et ESCP<\/a><\/li>\n<li><a href=\"https:\/\/groupe-reussite.fr\/ressources\/blog\/comment-integrer-hec\/\">Comment int\u00e9grer HEC ?<\/a><\/li>\n<li><a href=\"https:\/\/groupe-reussite.fr\/ressources\/blog\/ficher-cours-prepa-hec\/\">Comment ficher le cours en pr\u00e9pa ECG ?<\/a><\/li>\n<li><a href=\"https:\/\/groupe-reussite.fr\/ressources\/blog\/oral-maths-concours-prepa-hec\/\">Les oraux de maths en pr\u00e9pa ECG : HEC et ESCP<\/a><\/li>\n<li><a href=\"https:\/\/groupe-reussite.fr\/ressources\/blog\/differences-prepa-ecole\/\">Les diff\u00e9rentes entre la pr\u00e9pa ECG et l&rsquo;\u00e9cole de commerce<\/a><\/li>\n<li><a href=\"https:\/\/groupe-reussite.fr\/ressources\/blog\/passer-ecricome\/\">Faut-il passer Ecricome ?<\/a><\/li>\n<li><a href=\"https:\/\/groupe-reussite.fr\/ressources\/blog\/choisir-centre-examen-bce\/\">Les centres d&rsquo;examen BCE<\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>80 % des \u00e9l\u00e8ves Groupe R\u00e9ussite dans le Top 6 des \u00e9coles de commerce : 80% des \u00e9l\u00e8ves en pr\u00e9pa ECG qui ont d\u00e9cid\u00e9 de se faire accompagner par Groupe R\u00e9ussite, que ce soit en cours particuliers ou durant nos stages intensifs de vacances d\u00e9crochent l&rsquo;admissibilit\u00e9 et entrent dans le top 6 des \u00e9coles de [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":68960,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.2.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Avis et r\u00e9sultats en prepa ECG des \u00e9l\u00e8ves Groupe R\u00e9ussite<\/title>\n<meta name=\"description\" content=\"80% des \u00e9l\u00e8ves de Groupe R\u00e9ussite int\u00e8grent le top 6 des \u00e9coles et 95% d&#039;entre eux int\u00e8grent le top 10 des \u00e9coles de commerce de France.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/groupe-reussite.fr\/ressources\/blog\/resultats-eleves-prepa-hec\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avis et r\u00e9sultats en prepa ECG des \u00e9l\u00e8ves Groupe R\u00e9ussite\" \/>\n<meta property=\"og:description\" content=\"80% des \u00e9l\u00e8ves de Groupe R\u00e9ussite int\u00e8grent le top 6 des \u00e9coles et 95% d&#039;entre eux int\u00e8grent le top 10 des \u00e9coles de commerce de France.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/groupe-reussite.fr\/ressources\/blog\/resultats-eleves-prepa-hec\/\" \/>\n<meta property=\"og:site_name\" content=\"Groupe R\u00e9ussite\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GroupeReussiteOfficiel\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-22T10:33:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-17T15:23:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2020\/09\/resultats-prepa-hec-eleves-groupe-reussite.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"691\" \/>\n\t<meta property=\"og:image:height\" content=\"395\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Aghilas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@GroupeReussite\" \/>\n<meta name=\"twitter:site\" content=\"@GroupeReussite\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Aghilas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":[\"Article\",\"BlogPosting\"],\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/blog\/resultats-eleves-prepa-hec\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/blog\/resultats-eleves-prepa-hec\/\"},\"author\":{\"name\":\"Aghilas\",\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/#\/schema\/person\/b8341a7d54d9ca4655d5cb55682930e9\"},\"headline\":\"R\u00e9sultats et avis des \u00e9l\u00e8ves Groupe R\u00e9ussite en pr\u00e9pa ECG\",\"datePublished\":\"2020-09-22T10:33:31+00:00\",\"dateModified\":\"2026-06-17T15:23:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/blog\/resultats-eleves-prepa-hec\/\"},\"wordCount\":1825,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/#organization\"},\"articleSection\":[\"Prepa HEC\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/groupe-reussite.fr\/ressources\/blog\/resultats-eleves-prepa-hec\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/blog\/resultats-eleves-prepa-hec\/\",\"url\":\"https:\/\/groupe-reussite.fr\/ressources\/blog\/resultats-eleves-prepa-hec\/\",\"name\":\"Avis et r\u00e9sultats en prepa ECG des \u00e9l\u00e8ves Groupe R\u00e9ussite\",\"isPartOf\":{\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/#website\"},\"datePublished\":\"2020-09-22T10:33:31+00:00\",\"dateModified\":\"2026-06-17T15:23:01+00:00\",\"description\":\"80% des \u00e9l\u00e8ves de Groupe R\u00e9ussite int\u00e8grent le top 6 des \u00e9coles et 95% d'entre eux int\u00e8grent le top 10 des \u00e9coles de commerce de France.\",\"breadcrumb\":{\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/blog\/resultats-eleves-prepa-hec\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/groupe-reussite.fr\/ressources\/blog\/resultats-eleves-prepa-hec\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/blog\/resultats-eleves-prepa-hec\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/groupe-reussite.fr\/ressources\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prepa HEC\",\"item\":\"https:\/\/groupe-reussite.fr\/ressources\/blog\/category\/prepa-hec\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"R\u00e9sultats et avis des \u00e9l\u00e8ves Groupe R\u00e9ussite en pr\u00e9pa ECG\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/#website\",\"url\":\"https:\/\/groupe-reussite.fr\/ressources\/\",\"name\":\"Groupe R\u00e9ussite - Cours particuliers et stages de vacances\",\"description\":\"Stage et Cours particuliers maths, fran\u00e7ais, anglais, informatique, physique chimie\",\"publisher\":{\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/groupe-reussite.fr\/ressources\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/#organization\",\"name\":\"Groupe R\u00e9ussite - Cours particuliers et stages de vacances\",\"url\":\"https:\/\/groupe-reussite.fr\/ressources\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2026\/05\/logo-groupe-reussite-carre.png\",\"contentUrl\":\"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2026\/05\/logo-groupe-reussite-carre.png\",\"width\":170,\"height\":180,\"caption\":\"Groupe R\u00e9ussite - Cours particuliers et stages de vacances\"},\"image\":{\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/GroupeReussiteOfficiel\/\",\"https:\/\/twitter.com\/GroupeReussite\",\"https:\/\/www.youtube.com\/c\/GroupeReussite\",\"https:\/\/www.instagram.com\/groupe_reussite_officiel\/\",\"https:\/\/fr.linkedin.com\/company\/groupe-reussite\",\"https:\/\/www.tiktok.com\/@groupereussite\",\"https:\/\/fr.pinterest.com\/GroupeReussite\/\",\"https:\/\/www.reddit.com\/user\/Groupe-Reussite\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/groupe-reussite.fr\/ressources\/#\/schema\/person\/b8341a7d54d9ca4655d5cb55682930e9\",\"name\":\"Aghilas\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Avis et r\u00e9sultats en prepa ECG des \u00e9l\u00e8ves Groupe R\u00e9ussite","description":"80% des \u00e9l\u00e8ves de Groupe R\u00e9ussite int\u00e8grent le top 6 des \u00e9coles et 95% d'entre eux int\u00e8grent le top 10 des \u00e9coles de commerce de France.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/groupe-reussite.fr\/ressources\/blog\/resultats-eleves-prepa-hec\/","og_locale":"fr_FR","og_type":"article","og_title":"Avis et r\u00e9sultats en prepa ECG des \u00e9l\u00e8ves Groupe R\u00e9ussite","og_description":"80% des \u00e9l\u00e8ves de Groupe R\u00e9ussite int\u00e8grent le top 6 des \u00e9coles et 95% d'entre eux int\u00e8grent le top 10 des \u00e9coles de commerce de France.","og_url":"https:\/\/groupe-reussite.fr\/ressources\/blog\/resultats-eleves-prepa-hec\/","og_site_name":"Groupe R\u00e9ussite","article_publisher":"https:\/\/www.facebook.com\/GroupeReussiteOfficiel\/","article_published_time":"2020-09-22T10:33:31+00:00","article_modified_time":"2026-06-17T15:23:01+00:00","og_image":[{"width":691,"height":395,"url":"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2020\/09\/resultats-prepa-hec-eleves-groupe-reussite.jpg","type":"image\/jpeg"}],"author":"Aghilas","twitter_card":"summary_large_image","twitter_creator":"@GroupeReussite","twitter_site":"@GroupeReussite","twitter_misc":{"\u00c9crit par":"Aghilas","Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["Article","BlogPosting"],"@id":"https:\/\/groupe-reussite.fr\/ressources\/blog\/resultats-eleves-prepa-hec\/#article","isPartOf":{"@id":"https:\/\/groupe-reussite.fr\/ressources\/blog\/resultats-eleves-prepa-hec\/"},"author":{"name":"Aghilas","@id":"https:\/\/groupe-reussite.fr\/ressources\/#\/schema\/person\/b8341a7d54d9ca4655d5cb55682930e9"},"headline":"R\u00e9sultats et avis des \u00e9l\u00e8ves Groupe R\u00e9ussite en pr\u00e9pa ECG","datePublished":"2020-09-22T10:33:31+00:00","dateModified":"2026-06-17T15:23:01+00:00","mainEntityOfPage":{"@id":"https:\/\/groupe-reussite.fr\/ressources\/blog\/resultats-eleves-prepa-hec\/"},"wordCount":1825,"commentCount":0,"publisher":{"@id":"https:\/\/groupe-reussite.fr\/ressources\/#organization"},"articleSection":["Prepa HEC"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/groupe-reussite.fr\/ressources\/blog\/resultats-eleves-prepa-hec\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/groupe-reussite.fr\/ressources\/blog\/resultats-eleves-prepa-hec\/","url":"https:\/\/groupe-reussite.fr\/ressources\/blog\/resultats-eleves-prepa-hec\/","name":"Avis et r\u00e9sultats en prepa ECG des \u00e9l\u00e8ves Groupe R\u00e9ussite","isPartOf":{"@id":"https:\/\/groupe-reussite.fr\/ressources\/#website"},"datePublished":"2020-09-22T10:33:31+00:00","dateModified":"2026-06-17T15:23:01+00:00","description":"80% des \u00e9l\u00e8ves de Groupe R\u00e9ussite int\u00e8grent le top 6 des \u00e9coles et 95% d'entre eux int\u00e8grent le top 10 des \u00e9coles de commerce de France.","breadcrumb":{"@id":"https:\/\/groupe-reussite.fr\/ressources\/blog\/resultats-eleves-prepa-hec\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/groupe-reussite.fr\/ressources\/blog\/resultats-eleves-prepa-hec\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/groupe-reussite.fr\/ressources\/blog\/resultats-eleves-prepa-hec\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/groupe-reussite.fr\/ressources\/"},{"@type":"ListItem","position":2,"name":"Prepa HEC","item":"https:\/\/groupe-reussite.fr\/ressources\/blog\/category\/prepa-hec\/"},{"@type":"ListItem","position":3,"name":"R\u00e9sultats et avis des \u00e9l\u00e8ves Groupe R\u00e9ussite en pr\u00e9pa ECG"}]},{"@type":"WebSite","@id":"https:\/\/groupe-reussite.fr\/ressources\/#website","url":"https:\/\/groupe-reussite.fr\/ressources\/","name":"Groupe R\u00e9ussite - Cours particuliers et stages de vacances","description":"Stage et Cours particuliers maths, fran\u00e7ais, anglais, informatique, physique chimie","publisher":{"@id":"https:\/\/groupe-reussite.fr\/ressources\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/groupe-reussite.fr\/ressources\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/groupe-reussite.fr\/ressources\/#organization","name":"Groupe R\u00e9ussite - Cours particuliers et stages de vacances","url":"https:\/\/groupe-reussite.fr\/ressources\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/groupe-reussite.fr\/ressources\/#\/schema\/logo\/image\/","url":"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2026\/05\/logo-groupe-reussite-carre.png","contentUrl":"https:\/\/groupe-reussite.fr\/ressources\/wp-content\/uploads\/2026\/05\/logo-groupe-reussite-carre.png","width":170,"height":180,"caption":"Groupe R\u00e9ussite - Cours particuliers et stages de vacances"},"image":{"@id":"https:\/\/groupe-reussite.fr\/ressources\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GroupeReussiteOfficiel\/","https:\/\/twitter.com\/GroupeReussite","https:\/\/www.youtube.com\/c\/GroupeReussite","https:\/\/www.instagram.com\/groupe_reussite_officiel\/","https:\/\/fr.linkedin.com\/company\/groupe-reussite","https:\/\/www.tiktok.com\/@groupereussite","https:\/\/fr.pinterest.com\/GroupeReussite\/","https:\/\/www.reddit.com\/user\/Groupe-Reussite\/"]},{"@type":"Person","@id":"https:\/\/groupe-reussite.fr\/ressources\/#\/schema\/person\/b8341a7d54d9ca4655d5cb55682930e9","name":"Aghilas"}]}},"_links":{"self":[{"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/posts\/68811"}],"collection":[{"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/comments?post=68811"}],"version-history":[{"count":5,"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/posts\/68811\/revisions"}],"predecessor-version":[{"id":251036,"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/posts\/68811\/revisions\/251036"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/media\/68960"}],"wp:attachment":[{"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/media?parent=68811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/categories?post=68811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/groupe-reussite.fr\/ressources\/wp-json\/wp\/v2\/tags?post=68811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}